{"id":9221,"date":"2023-05-15T12:25:37","date_gmt":"2023-05-15T15:25:37","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=9221"},"modified":"2023-05-15T12:25:38","modified_gmt":"2023-05-15T15:25:38","slug":"por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/","title":{"rendered":"Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Cada vez hay m\u00e1s<a href=\"https:\/\/launion.com.ar\/nota\/27734\/2023\/04\/yrigoyen-y-pereyra-lucena-la-esquina-donde-se-cocinaron-grandes-decisiones\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;alternativas para moverse por la ciudad:&nbsp;<\/a>desde los tradicionales autos y motos particulares, la bici, el remis, el colectivo, la combi y el tren hasta los m\u00e1s novedosos, como los monopatines el\u00e9ctricos y las apps de transporte como Uber, Cafify o Didi.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/launion.com.ar\/nota\/28116\/2023\/05\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\" target=\"_blank\" rel=\"noreferrer noopener\">Pero (bastantes) a\u00f1os atr\u00e1s exist\u00eda en<\/a><strong><a href=\"https:\/\/launion.com.ar\/nota\/28116\/2023\/05\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Lomas de Zamora\u00a0<\/a><\/strong><a href=\"https:\/\/launion.com.ar\/nota\/28116\/2023\/05\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\" target=\"_blank\" rel=\"noreferrer noopener\">otra opci\u00f3n,<\/a>\u00a0una que quiz\u00e1s los m\u00e1s grandes (como yo) todav\u00eda recuerden: el\u00a0<strong>tranv\u00eda<\/strong>. Siempre guard\u00e9 aquellos viejos rieles en mi memoria y es por eso que hoy, en las p\u00e1ginas de La Uni\u00f3n, me gustar\u00eda compartirles su historia.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Corr\u00edan los primeros meses de 1866, con el partido Lomas reci\u00e9n fundado, cuando se inaugur\u00f3 un tranv\u00eda a caballo que iba de Constituci\u00f3n a Barracas. A\u00f1os m\u00e1s tarde, la compa\u00f1\u00eda, que era de capitales ingleses, habilit\u00f3 el servicio los domingos y feriados, llegando hasta nuestra zona. Como parte del proyecto se tendieron nuevas v\u00edas uniendo\u00a0<strong>Lomas con Temperley, Banfield con Villa Albertina, Temperley con Villa Sastre e Hip\u00f3dromo de Temperley con Puente Francia,<\/strong>\u00a0por ejemplo.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reci\u00e9n en 1906 el tranv\u00eda el\u00e9ctrico reemplaz\u00f3 al de tracci\u00f3n a sangre. Aquellos coches, muy recordados, eran de color granate y hac\u00edan un recorrido entre&nbsp;<strong>Plaza de Mayo y Temperley<\/strong>. Pese a realizar casi el mismo trayecto que el ferrocarril, el tranv\u00eda no era una competencia porque tardaba el doble de tiempo: el recorrido en nuestra ciudad lo hac\u00eda por la actual avenida&nbsp;<strong>Hip\u00f3lito Yrigoyen, Rodr\u00edguez Pe\u00f1a, Leandro N. Alem, Boedo, Carlos Pellegrini, Meeks y laestaci\u00f3n de Temperley.<\/strong>&nbsp;En el regreso iba por&nbsp;<strong>Meeks, Laprida, Alem, French y de nuevo Pav\u00f3n<\/strong>, siguiendo por los<strong>&nbsp;Talleres de Remedios de Escalada, Lan\u00fas, La Mosca, Gerli, Pi\u00f1eiro y Avellaneda<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En total demoraba 1 hora y 20 minutos. El tren tardaba 40. Pese a la tardanza, los vecinos igual lo usaban mucho para moverse en distancias cortas. \u00bfEl colectivo, se preguntar\u00e1n ustedes? El primero reci\u00e9n empez\u00f3 a andar en 1924.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La aparici\u00f3n del &#8220;bondi&#8221; signific\u00f3 fuerte golpe para el servicio del tranv\u00eda, ya que la gente dej\u00f3 de usarlo con tanta frecuencia. El tiro de gracia ocurri\u00f3 en la ma\u00f1ana del 12 de julio de 1930, cuando un coche sufri\u00f3 un desperfecto y cay\u00f3 Riachuelo con 56 pasajeros a bordo. S\u00f3lo cuatro sobrevivieron a la tragedia, que sali\u00f3 en todos los diarios y caus\u00f3 conmoci\u00f3n en la \u00e9poca.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos factores, sumados al desarrollo cada vez m\u00e1s imparable del ferrocarril, le fueron quitando atractivo y el viejo tranv\u00eda fue perdiendo pasajeros. Lo cerraron en 1948, cuando se levantaron las v\u00edas de la vieja avenida Pav\u00f3n para su pavimentaci\u00f3n definitiva. De todas formas, muchas otras v\u00edas, incrustadas en nuestras calles empedradas, siguieron visibles hasta fines de la d\u00e9cada del 60, principios del 70, cuando quedaron tapadas por nuevas capas de asfalto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ed: las viejas v\u00edas del tranv\u00eda siguen escondidas en nuestras calles. Son pedazos de nuestra historia que algunos de nuestros vecinos recordar\u00e1n. Nos encontramos la semana que viene, con otra historia sobre el barrio que tanto queremos.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em><a href=\"https:\/\/launion.com.ar\/nota\/28309\/2023\/05\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\" target=\"_blank\" rel=\"noreferrer noopener\">Art\u00edculo publicado en el diario La Uni\u00f3n de Lomas de Zamora.-<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada vez hay m\u00e1s&nbsp;alternativas para moverse por la ciudad:&nbsp;desde los tradicionales autos y motos particulares, la bici, el remis, el colectivo, la combi y el tren hasta los m\u00e1s novedosos, como los monopatines el\u00e9ctricos y las apps de transporte como Uber, Cafify o Didi.&nbsp;&nbsp; Pero (bastantes) a\u00f1os atr\u00e1s exist\u00eda en\u00a0Lomas de Zamora\u00a0otra opci\u00f3n,\u00a0una que quiz\u00e1s [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1276],"tags":[1557,1323,1277,2505],"class_list":["post-9221","post","type-post","status-publish","format-standard","has-post-thumbnail","category-de-puno-y-letra-lomas-de-zamora","tag-de-puno-y-letra-lomas-de-zamora","tag-la-union","tag-lomas-de-zamora","tag-tranvia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora - Sergio Lapegue<\/title>\n<meta name=\"description\" content=\"Reci\u00e9n en 1906 el tranv\u00eda el\u00e9ctrico reemplaz\u00f3 al de tracci\u00f3n a sangre. Un\u00eda Temperley con Plaza Constituci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"Reci\u00e9n en 1906 el tranv\u00eda el\u00e9ctrico reemplaz\u00f3 al de tracci\u00f3n a sangre. Un\u00eda Temperley con Plaza Constituci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-15T15:25:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-15T15:25:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/1344278098_captura_de_pantalla_2012_08_06_a_las_143435.png\" \/>\n\t<meta property=\"og:image:width\" content=\"564\" \/>\n\t<meta property=\"og:image:height\" content=\"369\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sergio Lapegue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sergiolapegue\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Lapegue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/\"},\"author\":{\"name\":\"Sergio Lapegue\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"headline\":\"Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora\",\"datePublished\":\"2023-05-15T15:25:37+00:00\",\"dateModified\":\"2023-05-15T15:25:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/\"},\"wordCount\":569,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/1344278098_captura_de_pantalla_2012_08_06_a_las_143435.png\",\"keywords\":[\"De Pu\u00f1o y Letra Lomas de Zamora\",\"La Uni\u00f3n\",\"Lomas de Zamora\",\"tranv\u00eda\"],\"articleSection\":[\"De Pu\u00f1o y Letra Lomas de Zamora\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/\",\"name\":\"Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/1344278098_captura_de_pantalla_2012_08_06_a_las_143435.png\",\"datePublished\":\"2023-05-15T15:25:37+00:00\",\"dateModified\":\"2023-05-15T15:25:38+00:00\",\"description\":\"Reci\u00e9n en 1906 el tranv\u00eda el\u00e9ctrico reemplaz\u00f3 al de tracci\u00f3n a sangre. Un\u00eda Temperley con Plaza Constituci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/1344278098_captura_de_pantalla_2012_08_06_a_las_143435.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/1344278098_captura_de_pantalla_2012_08_06_a_las_143435.png\",\"width\":564,\"height\":369},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/15\\\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/sergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora - Sergio Lapegue","description":"Reci\u00e9n en 1906 el tranv\u00eda el\u00e9ctrico reemplaz\u00f3 al de tracci\u00f3n a sangre. Un\u00eda Temperley con Plaza Constituci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora - Sergio Lapegue","og_description":"Reci\u00e9n en 1906 el tranv\u00eda el\u00e9ctrico reemplaz\u00f3 al de tracci\u00f3n a sangre. Un\u00eda Temperley con Plaza Constituci\u00f3n.","og_url":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2023-05-15T15:25:37+00:00","article_modified_time":"2023-05-15T15:25:38+00:00","og_image":[{"width":564,"height":369,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/1344278098_captura_de_pantalla_2012_08_06_a_las_143435.png","type":"image\/png"}],"author":"Sergio Lapegue","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sergiolapegue","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Sergio Lapegue","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/"},"author":{"name":"Sergio Lapegue","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"headline":"Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora","datePublished":"2023-05-15T15:25:37+00:00","dateModified":"2023-05-15T15:25:38+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/"},"wordCount":569,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/1344278098_captura_de_pantalla_2012_08_06_a_las_143435.png","keywords":["De Pu\u00f1o y Letra Lomas de Zamora","La Uni\u00f3n","Lomas de Zamora","tranv\u00eda"],"articleSection":["De Pu\u00f1o y Letra Lomas de Zamora"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/","url":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/","name":"Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/1344278098_captura_de_pantalla_2012_08_06_a_las_143435.png","datePublished":"2023-05-15T15:25:37+00:00","dateModified":"2023-05-15T15:25:38+00:00","description":"Reci\u00e9n en 1906 el tranv\u00eda el\u00e9ctrico reemplaz\u00f3 al de tracci\u00f3n a sangre. Un\u00eda Temperley con Plaza Constituci\u00f3n.","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/1344278098_captura_de_pantalla_2012_08_06_a_las_143435.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/1344278098_captura_de_pantalla_2012_08_06_a_las_143435.png","width":564,"height":369},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/15\/por-que-dejo-de-existir-el-tranvia-en-lomas-de-zamora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 dej\u00f3 de existir el tranv\u00eda en Lomas de Zamora"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"],"url":"https:\/\/sergiolapegue.com\/site\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/9221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=9221"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/9221\/revisions"}],"predecessor-version":[{"id":9223,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/9221\/revisions\/9223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/9222"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=9221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=9221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=9221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}