{"id":9122,"date":"2023-05-08T12:40:54","date_gmt":"2023-05-08T15:40:54","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=9122"},"modified":"2023-05-08T12:40:55","modified_gmt":"2023-05-08T15:40:55","slug":"el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/","title":{"rendered":"El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a1Hola de nuevo, queridos amigos de&nbsp;<strong>La Uni\u00f3n<\/strong>! Ustedes saben mejor que nadie lo mucho que disfruto cont\u00e1ndoles las historias de los edificios, las calles y los personajes m\u00e1s c\u00e9lebres de nuestro partido. Pero tambi\u00e9n me gusta rescatar la vida de los vecinos comunes, esos que quiz\u00e1s no llegaron a ser importantes pol\u00edticos, artistas o deportistas, pero s\u00ed vivieron&nbsp;<a href=\"https:\/\/launion.com.ar\/nota\/27734\/2023\/04\/yrigoyen-y-pereyra-lucena-la-esquina-donde-se-cocinaron-grandes-decisiones\" target=\"_blank\" rel=\"noreferrer noopener\">historias emocionantes que a\u00fan son recordadas.&nbsp;&nbsp;<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy les voy a hablar del caso de<strong>\u00a0Juan Losardo y Horacio Lozano<\/strong>, dos lomenses que 65 a\u00f1os atr\u00e1s se embarcaron con un objetivo incre\u00edble: llegar desde\u00a0<strong><a href=\"https:\/\/launion.com.ar\/nota\/27544\/2023\/04\/el-doble-crimen-que-marco-la-decadencia-del-bar-el-tripoli-en-lomas\" target=\"_blank\" rel=\"noreferrer noopener\">Lomas de Zamora<\/a>\u00a0hasta Nueva York<\/strong>. \u00bfEn auto? No. \u00bfEn avi\u00f3n? Menos. Los amigos planearon su viaje de miles de kil\u00f3metros&#8230; \u00a1en carreta!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al empezar el viaje, el 12 de mayo de 1958,\u00a0<strong>Losardo y Lozano<\/strong>\u00a0no ten\u00edan ning\u00fan tipo de experiencia en viajes largos y mucho menos en el tipo de veh\u00edculo que eligieron. Eso s\u00ed: ten\u00edan dos fieles caballos llamados Bocha y Piba y un objetivo en concreto: que la ruta Panamericana fuera renombrada como\u00a0<strong>Nuestra Se\u00f1ora de La Paz.<\/strong>\u00a0Los amigos salieron entonces desde la\u00a0<strong>Plaza Grigera<\/strong>\u00a0por la<strong>\u00a0avenida Pav\u00f3n<\/strong>\u00a0hasta el Congreso de la Naci\u00f3n, punto de partida oficial de la traves\u00eda por ser el kil\u00f3metro 0 de Argentina. En Lomas, los despidieron el recordado monse\u00f1or Alejandro Schell y el por entonces intendente Adri\u00e1n Boffi.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La haza\u00f1a de los amigos lomenses fue contada por todos los diarios nacionales de la \u00e9poca. Y su difusi\u00f3n ayud\u00f3 para que&nbsp;<strong>Losardo y Lozano<\/strong>&nbsp;recibieran apoyo econ\u00f3mico de las autoridades. Pero lo m\u00e1s importante, claro, era el cari\u00f1o de la gente que los recib\u00eda en cada pueblo con una sonrisa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los viajeros tuvieron miles de complicaciones en la ruta. El primer contratiempo ocurri\u00f3 en la avenida Rivadavia hacia el oeste, ya que los caballos no estaban acostumbrados al asfalto y se resbalaban constantemente. Superados los percances, tomaron la avenida General Paz rumbo al norte, ya con la br\u00fajula enfocando a la Gran Manzana.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al salir del pa\u00eds aparecieron m\u00e1s problemas: en Bolivia no les permit\u00edan cruzar con caballos, en Per\u00fa excedieron el plazo de estad\u00eda para extranjeros y en Colombia, un grupo de ladrones intent\u00f3 asaltarlos a punta de pistola. Pero siguieron adelante. Pasaron Panam\u00e1, Honduras, Costa Rica y Nicaragua. Finalmente, en Guatemala, muy cerca de la frontera con M\u00e9xico, el desgaste personal (<strong>Losardo<\/strong>&nbsp;se enferm\u00f3 de fiebre tifoidea, tuvo que ser internado y luego tra\u00eddo de vuelta al pa\u00eds) y de los animales (llevaban dos a\u00f1os y medio en la ruta) los oblig\u00f3 a terminar la odisea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lozano se qued\u00f3 un tiempo m\u00e1s para ubicar la diligencia y a los caballos, que encontraron un nuevo hogar en una hacienda guatemalteca. En fin, el sue\u00f1o de los amigos no se logr\u00f3, pero s\u00ed vivieron una historia incre\u00edble. \u00a1Hasta la semana que viene!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em><a href=\"https:\/\/launion.com.ar\/nota\/28116\/2023\/05\/el-suentildeo-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\" target=\"_blank\" rel=\"noreferrer noopener\">Art\u00edculo publicado en el diario La Uni\u00f3n de Lomas de Zamora.-<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Hola de nuevo, queridos amigos de&nbsp;La Uni\u00f3n! Ustedes saben mejor que nadie lo mucho que disfruto cont\u00e1ndoles las historias de los edificios, las calles y los personajes m\u00e1s c\u00e9lebres de nuestro partido. Pero tambi\u00e9n me gusta rescatar la vida de los vecinos comunes, esos que quiz\u00e1s no llegaron a ser importantes pol\u00edticos, artistas o deportistas, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1276],"tags":[1557,1323,1277,2493],"class_list":["post-9122","post","type-post","status-publish","format-standard","has-post-thumbnail","category-de-puno-y-letra-lomas-de-zamora","tag-de-puno-y-letra-lomas-de-zamora","tag-la-union","tag-lomas-de-zamora","tag-viajes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea - Sergio Lapegue<\/title>\n<meta name=\"description\" content=\"Juan Losardo y Horacio Lozano emprendieron hace seis d\u00e9cadas atr\u00e1s con un objetivo incre\u00edble: ir de Lomas a Nueva York en carreta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"Juan Losardo y Horacio Lozano emprendieron hace seis d\u00e9cadas atr\u00e1s con un objetivo incre\u00edble: ir de Lomas a Nueva York en carreta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-08T15:40:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-08T15:40:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/169419.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sergio Lapegue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sergiolapegue\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Lapegue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/\"},\"author\":{\"name\":\"Sergio Lapegue\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"headline\":\"El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea\",\"datePublished\":\"2023-05-08T15:40:54+00:00\",\"dateModified\":\"2023-05-08T15:40:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/\"},\"wordCount\":539,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/169419.jpg\",\"keywords\":[\"De Pu\u00f1o y Letra Lomas de Zamora\",\"La Uni\u00f3n\",\"Lomas de Zamora\",\"viajes\"],\"articleSection\":[\"De Pu\u00f1o y Letra Lomas de Zamora\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/\",\"name\":\"El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/169419.jpg\",\"datePublished\":\"2023-05-08T15:40:54+00:00\",\"dateModified\":\"2023-05-08T15:40:55+00:00\",\"description\":\"Juan Losardo y Horacio Lozano emprendieron hace seis d\u00e9cadas atr\u00e1s con un objetivo incre\u00edble: ir de Lomas a Nueva York en carreta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/169419.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/169419.jpg\",\"width\":1000,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/05\\\/08\\\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/sergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea - Sergio Lapegue","description":"Juan Losardo y Horacio Lozano emprendieron hace seis d\u00e9cadas atr\u00e1s con un objetivo incre\u00edble: ir de Lomas a Nueva York en carreta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/","og_locale":"es_ES","og_type":"article","og_title":"El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea - Sergio Lapegue","og_description":"Juan Losardo y Horacio Lozano emprendieron hace seis d\u00e9cadas atr\u00e1s con un objetivo incre\u00edble: ir de Lomas a Nueva York en carreta.","og_url":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2023-05-08T15:40:54+00:00","article_modified_time":"2023-05-08T15:40:55+00:00","og_image":[{"width":1000,"height":525,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/169419.jpg","type":"image\/jpeg"}],"author":"Sergio Lapegue","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sergiolapegue","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Sergio Lapegue","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/"},"author":{"name":"Sergio Lapegue","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"headline":"El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea","datePublished":"2023-05-08T15:40:54+00:00","dateModified":"2023-05-08T15:40:55+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/"},"wordCount":539,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/169419.jpg","keywords":["De Pu\u00f1o y Letra Lomas de Zamora","La Uni\u00f3n","Lomas de Zamora","viajes"],"articleSection":["De Pu\u00f1o y Letra Lomas de Zamora"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/","url":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/","name":"El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/169419.jpg","datePublished":"2023-05-08T15:40:54+00:00","dateModified":"2023-05-08T15:40:55+00:00","description":"Juan Losardo y Horacio Lozano emprendieron hace seis d\u00e9cadas atr\u00e1s con un objetivo incre\u00edble: ir de Lomas a Nueva York en carreta.","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/169419.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/05\/169419.jpg","width":1000,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2023\/05\/08\/el-sueno-de-dos-amigos-lomenses-que-se-convirtio-en-odisea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"El sue\u00f1o de dos amigos lomenses que se convirti\u00f3 en odisea"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"],"url":"https:\/\/sergiolapegue.com\/site\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/9122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=9122"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/9122\/revisions"}],"predecessor-version":[{"id":9128,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/9122\/revisions\/9128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/9127"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=9122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=9122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=9122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}