{"id":8215,"date":"2023-03-13T11:09:22","date_gmt":"2023-03-13T14:09:22","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=8215"},"modified":"2023-03-13T11:09:48","modified_gmt":"2023-03-13T14:09:48","slug":"diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/","title":{"rendered":"Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a1Hola de nuevo,<a href=\"https:\/\/launion.com.ar\/nota\/26376\/2023\/03\/el-recuerdo-de-ver-la-noticias-de-la-union-en-las-pizarras-negras\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;queridos amigos de&nbsp;<\/a><strong><a href=\"https:\/\/launion.com.ar\/nota\/26376\/2023\/03\/el-recuerdo-de-ver-la-noticias-de-la-union-en-las-pizarras-negras\" target=\"_blank\" rel=\"noreferrer noopener\">La Uni\u00f3n<\/a><\/strong><a href=\"https:\/\/launion.com.ar\/nota\/26376\/2023\/03\/el-recuerdo-de-ver-la-noticias-de-la-union-en-las-pizarras-negras\" target=\"_blank\" rel=\"noreferrer noopener\">!&nbsp;<\/a>Estamos a horas de que se cumpla el d\u00e9cimo aniversario de una fecha important\u00edsima para todos los argentinos. Tan importante que seguramente recuerdes qu\u00e9 estabas haciendo en ese momento: el 13 de marzo de 2013, la famosa &#8220;<strong>fumata blanca&#8221;<\/strong>&nbsp;sal\u00eda del Vaticano y minutos despu\u00e9s, en una plaza San Pedro colmada por los fieles, el cardenal&nbsp;<strong>Jorge Mario Bergoglio&nbsp;<\/strong>se convert\u00eda en el&nbsp;<strong>Papa Francisco.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue un suceso hist\u00f3rico que miles de millones de personas siguieron por televisi\u00f3n y redes sociales. Se trat\u00f3 de la primera coronaci\u00f3n para un cura argentino como Sumo Pont\u00edfice y un orgullo para toda la comunidad cat\u00f3lica de Am\u00e9rica Latina. Aprovechando este aniversario, hoy me gustar\u00eda hablar \u2013como siempre\u2013 sobre una personalidad de<a href=\"https:\/\/launion.com.ar\/nota\/26254\/2023\/02\/domingo-cabred-la-historia-del-medico-que-tiene-un-barrio-en-su-nombre\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0<\/a><strong><a href=\"https:\/\/launion.com.ar\/nota\/26254\/2023\/02\/domingo-cabred-la-historia-del-medico-que-tiene-un-barrio-en-su-nombre\" target=\"_blank\" rel=\"noreferrer noopener\">Lomas de Zamora<\/a>.<\/strong>\u00a0Eleg\u00ed a monse\u00f1or\u00a0<strong>Alejandro Schell,<\/strong>\u00a0quiz\u00e1s la figura religiosa m\u00e1s importante de nuestro partido en toda su historia. \u00bfMe acompa\u00f1an?\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Schell<\/strong>&nbsp;naci\u00f3 el 9 de octubre de 1897, en Alemania. Tras llegar a Argentina, fue ordenado sacerdote en 1922 y en un principio se desempe\u00f1\u00f3 en San Isidro y Villa Ballester. Pero en 1931 lo enviaron a nuestro distrito para ser el p\u00e1rroco de la&nbsp;<strong><a href=\"https:\/\/launion.com.ar\/nota\/11995\/2021\/08\/las-visitas-de-jorge-bergoglio-a-la-catedral-de-lomas--en-2007-llego-en-tren\" target=\"_blank\" rel=\"noreferrer noopener\">Iglesia Nuestra Se\u00f1ora de la Paz,&nbsp;<\/a><\/strong><a href=\"https:\/\/launion.com.ar\/nota\/11995\/2021\/08\/las-visitas-de-jorge-bergoglio-a-la-catedral-de-lomas--en-2007-llego-en-tren\" target=\"_blank\" rel=\"noreferrer noopener\">la actual catedral.&nbsp;<\/a>Cuando en 1957 se cre\u00f3 la di\u00f3cesis de Lomas era Vicario General, es decir, el segundo de la jerarqu\u00eda eclesi\u00e1stica a nivel diocesano. Pero a pocos d\u00edas de haber iniciado su trabajo pastoral, el obispo&nbsp;<strong>Filem\u00f3n Castellano<\/strong>&nbsp;se enferm\u00f3 y debi\u00f3 renunciar. As\u00ed, en 1958, designado por P\u00edo XII por &#8220;las pruebas de su piedad y diligencia&#8221;,&nbsp;<strong>Schell<\/strong>&nbsp;se transform\u00f3 en el segundo Pastor de la Iglesia diocesana.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al padre Alejandro le toc\u00f3 la ardua tarea de organizar la nueva di\u00f3cesis, entonces conformada por los partidos de&nbsp;<strong>Lan\u00fas, Ca\u00f1uelas, Almirante Brown, Esteban Echeverr\u00eda, San Vicente y Lomas<\/strong>. Desde entonces y por 41 a\u00f1os, nuestras calles lo vieron transitar con su paso cansino y su imagen robusta, con un semblante bonach\u00f3n donde se destacaba su mirada de ojos celestes. Su pelo rubio y lacio, a veces con un mech\u00f3n rebelde en su generosa frente, constitu\u00edan la t\u00edpica fisonom\u00eda del pueblo germano. Quienes lo conocieron lo recuerdan como un cura de pueblo, muy cercano a la gente. Claro que la vida de aquella \u00e9poca ten\u00eda un ritmo m\u00e1s tranquilo que la actual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Catedral<\/strong>&nbsp;fue su casa. Para m\u00ed ese lugar representa mucho, porque fue en esa Iglesia donde se casaron mis padres en 1958, donde me bautizaron, donde tom\u00e9 la primera comuni\u00f3n y donde, en 1992, me cas\u00e9 con Silvita.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El recordado cura alem\u00e1n dej\u00f3 su huella en nuestro barrio. Hoy, el reconocimiento ciudadano puede apreciarse en el homenaje que el\u00a0<strong>Concejo Deliberante<\/strong>\u00a0local dispuso a poco de su muerte, en 1972, al darle su nombre a una calle del partido.\u00a0<strong>Monse\u00f1or Schell<\/strong>\u00a0nace en avenida Alsina, a cuatro cuadras de la estaci\u00f3n de Lomas, del lado este. \u00bfLa conoc\u00e9s?\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em><a href=\"https:\/\/launion.com.ar\/nota\/26607\/2023\/03\/diez-antildeos-del-papa-francisco-y-el-recuerdo-de-monsentildeor-schell-en-lomas\" target=\"_blank\" rel=\"noreferrer noopener\">Art\u00edculo publicado en el diario La Uni\u00f3n de Lomas de Zamora.-<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Hola de nuevo,&nbsp;queridos amigos de&nbsp;La Uni\u00f3n!&nbsp;Estamos a horas de que se cumpla el d\u00e9cimo aniversario de una fecha important\u00edsima para todos los argentinos. Tan importante que seguramente recuerdes qu\u00e9 estabas haciendo en ese momento: el 13 de marzo de 2013, la famosa &#8220;fumata blanca&#8221;&nbsp;sal\u00eda del Vaticano y minutos despu\u00e9s, en una plaza San Pedro colmada [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":8216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1276],"tags":[1557,1323,1277,2319,2318],"class_list":["post-8215","post","type-post","status-publish","format-standard","has-post-thumbnail","category-de-puno-y-letra-lomas-de-zamora","tag-de-puno-y-letra-lomas-de-zamora","tag-la-union","tag-lomas-de-zamora","tag-monsenor-schell","tag-papa-francisco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas - Sergio Lapegue<\/title>\n<meta name=\"description\" content=\"A una d\u00e9cada de la fumata blanca con la que Bergoglio se convert\u00eda Papa, recordamos a la figura religiosa m\u00e1s importante que tuvo Lomas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"A una d\u00e9cada de la fumata blanca con la que Bergoglio se convert\u00eda Papa, recordamos a la figura religiosa m\u00e1s importante que tuvo Lomas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-13T14:09:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-13T14:09:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/03\/165479.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sergio Lapegue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sergiolapegue\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Lapegue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/\"},\"author\":{\"name\":\"Sergio Lapegue\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"headline\":\"Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas\",\"datePublished\":\"2023-03-13T14:09:22+00:00\",\"dateModified\":\"2023-03-13T14:09:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/\"},\"wordCount\":561,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/165479.jpg\",\"keywords\":[\"De Pu\u00f1o y Letra Lomas de Zamora\",\"La Uni\u00f3n\",\"Lomas de Zamora\",\"Monse\u00f1or Schell\",\"Papa Francisco\"],\"articleSection\":[\"De Pu\u00f1o y Letra Lomas de Zamora\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/\",\"name\":\"Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/165479.jpg\",\"datePublished\":\"2023-03-13T14:09:22+00:00\",\"dateModified\":\"2023-03-13T14:09:48+00:00\",\"description\":\"A una d\u00e9cada de la fumata blanca con la que Bergoglio se convert\u00eda Papa, recordamos a la figura religiosa m\u00e1s importante que tuvo Lomas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/165479.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/165479.jpg\",\"width\":1000,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/03\\\/13\\\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/sergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas - Sergio Lapegue","description":"A una d\u00e9cada de la fumata blanca con la que Bergoglio se convert\u00eda Papa, recordamos a la figura religiosa m\u00e1s importante que tuvo Lomas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/","og_locale":"es_ES","og_type":"article","og_title":"Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas - Sergio Lapegue","og_description":"A una d\u00e9cada de la fumata blanca con la que Bergoglio se convert\u00eda Papa, recordamos a la figura religiosa m\u00e1s importante que tuvo Lomas.","og_url":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2023-03-13T14:09:22+00:00","article_modified_time":"2023-03-13T14:09:48+00:00","og_image":[{"width":1000,"height":525,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/03\/165479.jpg","type":"image\/jpeg"}],"author":"Sergio Lapegue","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sergiolapegue","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Sergio Lapegue","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/"},"author":{"name":"Sergio Lapegue","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"headline":"Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas","datePublished":"2023-03-13T14:09:22+00:00","dateModified":"2023-03-13T14:09:48+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/"},"wordCount":561,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/03\/165479.jpg","keywords":["De Pu\u00f1o y Letra Lomas de Zamora","La Uni\u00f3n","Lomas de Zamora","Monse\u00f1or Schell","Papa Francisco"],"articleSection":["De Pu\u00f1o y Letra Lomas de Zamora"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/","url":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/","name":"Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/03\/165479.jpg","datePublished":"2023-03-13T14:09:22+00:00","dateModified":"2023-03-13T14:09:48+00:00","description":"A una d\u00e9cada de la fumata blanca con la que Bergoglio se convert\u00eda Papa, recordamos a la figura religiosa m\u00e1s importante que tuvo Lomas.","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/03\/165479.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/03\/165479.jpg","width":1000,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2023\/03\/13\/diez-anos-del-papa-francisco-y-el-recuerdo-de-monsenor-schell-en-lomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"Diez a\u00f1os del Papa Francisco y el recuerdo de Monse\u00f1or Schell en Lomas"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"],"url":"https:\/\/sergiolapegue.com\/site\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/8215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=8215"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/8215\/revisions"}],"predecessor-version":[{"id":8217,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/8215\/revisions\/8217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/8216"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=8215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=8215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=8215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}