{"id":7395,"date":"2023-01-09T10:40:04","date_gmt":"2023-01-09T13:40:04","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=7395"},"modified":"2023-01-09T10:40:05","modified_gmt":"2023-01-09T13:40:05","slug":"otro-ano-otro-desfile-de-reyes-en-lomas","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/","title":{"rendered":"Otro a\u00f1o, otro desfile de Reyes en Lomas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No existe una fiesta m\u00e1s antigua y tradicional en&nbsp;<strong>Lomas de Zamora<\/strong>&nbsp;que la que, otra vez, se celebr\u00f3 el pasado jueves en las calles de nuestra ciudad: la del gran desfile de&nbsp;<strong>Reyes Magos<\/strong>. Como cada vez que empieza el a\u00f1o,&nbsp;<strong>Melchor<\/strong>,&nbsp;<strong>Gaspar<\/strong>&nbsp;y&nbsp;<strong>Baltasar<\/strong>&nbsp;alegraron a miles de chicos en una verdadera fiesta popular que atrae a vecinos de otras localidades y se repite desde hace\u2026 \u00a192 a\u00f1os!&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Organizado como siempre por el\u00a0<strong>C\u00edrculo Cat\u00f3lico de Obreros<\/strong>\u00a0(tambi\u00e9n suelen colaborar autoridades municipales, la C\u00e1mara de Comercio, Bomberos y Defensa Civil), comenz\u00f3 en\u00a0<strong>Laprida<\/strong>\u00a0y\u00a0<strong>Meeks<\/strong>\u00a0y finaliz\u00f3 en la sede la entidad, en\u00a0<strong>Hip\u00f3lito Yrigoyen<\/strong>\u00a0al 8400, casi\u00a0<strong>S\u00e1enz<\/strong>, donde montaron el escenario. Antes, por supuesto, los tres reyes recorrieron las calles c\u00e9ntricas, repartieron caramelos, recibieron cientos de cartas de los vecinos m\u00e1s chiquitos y recaudaron alimentos no perecederos que ser\u00e1n enviados a hogares y parroquias del distrito. Todo se complet\u00f3 con un show en inmediaciones de la\u00a0<strong>Plaza Grigera<\/strong>. A la medianoche los tres magos de Oriente se tuvieron que ir. Los camellos ten\u00edan hambre y sed y, claro, los juguetes no se entregan solos.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora bien, \u00bfc\u00f3mo naci\u00f3 la fiesta? Fueron justamente las autoridades del C\u00edrculo quienes en diciembre de 1928 organizaron la entrega de juguetes para chicos carenciados en el d\u00eda de Reyes. La idea, tra\u00edda de Espa\u00f1a Juan Jord\u00e1n, se concret\u00f3 el 6 de enero de 1929, y as\u00ed se dio el primer paso para llevar a cabo un proyecto que con el paso de los a\u00f1os fue creciendo cada vez m\u00e1s. Un a\u00f1o despu\u00e9s, en 1930, el C\u00edrculo resolvi\u00f3 organizar el reparto de juguetes y un gran desfile con actores en la noche del 5 de enero. Varias empresas cedieron sus carrozas para el paseo por las calles\u00a0<strong>Laprida\u00a0<\/strong>y\u00a0<strong>Rodr\u00edguez<\/strong>\u00a0mientras los juguetes eran distribuidos en camiones. El \u00e9xito de aquella juntada super\u00f3 todas las expectativas de los organizadores y por eso se decidi\u00f3 repetir el festejo a\u00f1o tras a\u00f1o, ininterrumpidamente hasta hoy.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El\u00a0<strong>desfile de Reyes de Lomas<\/strong>\u00a0es, sin dudas, una tradici\u00f3n de la ciudad. Cualquiera que haya crecido en nuestras calles tiene que recordar, al menos, haberlo visto. Yo lo tambi\u00e9n: pienso con mucha nostalgia y cari\u00f1o aquellos d\u00edas cuando mis padres me llevaban de pibe a ver a\u00a0<strong>Melchor<\/strong>,\u00a0<strong>Gaspar<\/strong>\u00a0y\u00a0<strong>Baltasar<\/strong>\u00a0en la plaza de\u00a0<strong>Lomas<\/strong>, antes de volver a casa y dejarles el agua y el pasto a los camellos. Cada inolvidable noche de Reyes sent\u00eda una mezcla de emoci\u00f3n, ansiedad, asombro y alegr\u00eda por ver a los hombres que ven\u00edan a alegrarnos desde Oriente. Son recuerdos tan lindos los que me evoca la celebraci\u00f3n que con el tiempo decid\u00ed repetir el ritual con mis hijos Micaela y Elvis, ahora disfrutando tambi\u00e9n el rol de padre. Si nunca fuiste, te lo recomiendo: eso s\u00ed, vas a tener que esperar hasta el 2024.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/launion.com.ar\/nota\/25022\/2023\/01\/otro-antildeo-otro-desfile-de-reyes-en-lomas\" target=\"_blank\" rel=\"noreferrer noopener\">Columna publicada en el diario La Uni\u00f3n de Lomas de Zamora.-<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No existe una fiesta m\u00e1s antigua y tradicional en&nbsp;Lomas de Zamora&nbsp;que la que, otra vez, se celebr\u00f3 el pasado jueves en las calles de nuestra ciudad: la del gran desfile de&nbsp;Reyes Magos. Como cada vez que empieza el a\u00f1o,&nbsp;Melchor,&nbsp;Gaspar&nbsp;y&nbsp;Baltasar&nbsp;alegraron a miles de chicos en una verdadera fiesta popular que atrae a vecinos de otras localidades [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":7396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1276],"tags":[2137,1323,1277,2136],"class_list":["post-7395","post","type-post","status-publish","format-standard","has-post-thumbnail","category-de-puno-y-letra-lomas-de-zamora","tag-desfile-de-reyes","tag-la-union","tag-lomas-de-zamora","tag-reyes-magos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Otro a\u00f1o, otro desfile de Reyes en Lomas - Sergio Lapegue<\/title>\n<meta name=\"description\" content=\"El desfile de Reyes es sin dudas una tradici\u00f3n de la ciudad. Cualquiera que haya crecido en las calles de Lomas de Zamora lo sabe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otro a\u00f1o, otro desfile de Reyes en Lomas - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"El desfile de Reyes es sin dudas una tradici\u00f3n de la ciudad. Cualquiera que haya crecido en las calles de Lomas de Zamora lo sabe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-09T13:40:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-09T13:40:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/01\/161445.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sergio Lapegue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sergiolapegue\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Lapegue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/\"},\"author\":{\"name\":\"Sergio Lapegue\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"headline\":\"Otro a\u00f1o, otro desfile de Reyes en Lomas\",\"datePublished\":\"2023-01-09T13:40:04+00:00\",\"dateModified\":\"2023-01-09T13:40:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/\"},\"wordCount\":536,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/161445.jpg\",\"keywords\":[\"Desfile de Reyes\",\"La Uni\u00f3n\",\"Lomas de Zamora\",\"Reyes Magos\"],\"articleSection\":[\"De Pu\u00f1o y Letra Lomas de Zamora\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/\",\"name\":\"Otro a\u00f1o, otro desfile de Reyes en Lomas - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/161445.jpg\",\"datePublished\":\"2023-01-09T13:40:04+00:00\",\"dateModified\":\"2023-01-09T13:40:05+00:00\",\"description\":\"El desfile de Reyes es sin dudas una tradici\u00f3n de la ciudad. Cualquiera que haya crecido en las calles de Lomas de Zamora lo sabe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/161445.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/161445.jpg\",\"width\":1000,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2023\\\/01\\\/09\\\/otro-ano-otro-desfile-de-reyes-en-lomas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otro a\u00f1o, otro desfile de Reyes en Lomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/sergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Otro a\u00f1o, otro desfile de Reyes en Lomas - Sergio Lapegue","description":"El desfile de Reyes es sin dudas una tradici\u00f3n de la ciudad. Cualquiera que haya crecido en las calles de Lomas de Zamora lo sabe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/","og_locale":"es_ES","og_type":"article","og_title":"Otro a\u00f1o, otro desfile de Reyes en Lomas - Sergio Lapegue","og_description":"El desfile de Reyes es sin dudas una tradici\u00f3n de la ciudad. Cualquiera que haya crecido en las calles de Lomas de Zamora lo sabe.","og_url":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2023-01-09T13:40:04+00:00","article_modified_time":"2023-01-09T13:40:05+00:00","og_image":[{"width":1000,"height":525,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/01\/161445.jpg","type":"image\/jpeg"}],"author":"Sergio Lapegue","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sergiolapegue","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Sergio Lapegue","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/"},"author":{"name":"Sergio Lapegue","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"headline":"Otro a\u00f1o, otro desfile de Reyes en Lomas","datePublished":"2023-01-09T13:40:04+00:00","dateModified":"2023-01-09T13:40:05+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/"},"wordCount":536,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/01\/161445.jpg","keywords":["Desfile de Reyes","La Uni\u00f3n","Lomas de Zamora","Reyes Magos"],"articleSection":["De Pu\u00f1o y Letra Lomas de Zamora"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/","url":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/","name":"Otro a\u00f1o, otro desfile de Reyes en Lomas - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/01\/161445.jpg","datePublished":"2023-01-09T13:40:04+00:00","dateModified":"2023-01-09T13:40:05+00:00","description":"El desfile de Reyes es sin dudas una tradici\u00f3n de la ciudad. Cualquiera que haya crecido en las calles de Lomas de Zamora lo sabe.","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/01\/161445.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2023\/01\/161445.jpg","width":1000,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2023\/01\/09\/otro-ano-otro-desfile-de-reyes-en-lomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"Otro a\u00f1o, otro desfile de Reyes en Lomas"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"],"url":"https:\/\/sergiolapegue.com\/site\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/7395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=7395"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/7395\/revisions"}],"predecessor-version":[{"id":7397,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/7395\/revisions\/7397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/7396"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=7395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=7395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=7395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}