{"id":3908,"date":"2022-04-04T16:07:10","date_gmt":"2022-04-04T19:07:10","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=3908"},"modified":"2022-04-04T16:07:11","modified_gmt":"2022-04-04T19:07:11","slug":"como-se-mide-la-vida-2","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/","title":{"rendered":"\u00bfC\u00f3mo se mide la vida?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo se mide la vida? No se mide por puntos, como si estuvieses en un juego. <strong>No se mide por la cantidad de amigos<\/strong> ni por c\u00f3mo te miran o te aceptan los dem\u00e1s. No se mide seg\u00fan los planes que tengas para el fin de semana. <strong>Tampoco seg\u00fan con qui\u00e9n sal\u00eds<\/strong>, con quien saliste o por el n\u00famero de personas con las que estuviste.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vida no se mide por tu fama ni la de tu familia; <strong>no se mide por el dinero que ten\u00e9s en el banco<\/strong>. La vida no se mide ni por la marca de tu ropa ni por la del auto que manej\u00e1s. No se mide por el lugar en el que estudi\u00e1s o trabaj\u00e1s.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vida es mucho m\u00e1s que todo eso. <strong>Se mide seg\u00fan a qui\u00e9n am\u00e1s o a quien lastim\u00e1s.<\/strong> Se mide seg\u00fan la felicidad o la tristeza que uno puede llegar a causarle a la otra persona. <strong>Se mide con los compromisos que uno cumple. \u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La vida se mide a trav\u00e9s de la amistad<\/strong>, la cual puede usarse como algo sagrado o como un arma. Se trata de lo que uno dice, pero m\u00e1s de lo que uno hace. <strong>De dar y de recibir.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si hay algo que nunca me perdonar\u00eda es ser falso. Siempre he cre\u00eddo que la clave del \u00e9xito est\u00e1 en que uno tiene que ser igual delante de una c\u00e1mara, el micr\u00f3fono de la radio, en la calle, en el gym o en casa. <strong>No sos distinto, ni m\u00e1s ni menos que nadie, por ser conocido<\/strong>. Sos el mismo, con tus alegr\u00edas y tristezas.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Solo vos eleg\u00eds la manera en la que vas a afectar a las otras personas<\/strong>. De esas decisiones, amigos, se trata la vida.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Te lo dice un amigo.<\/em><\/strong>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo se mide la vida? No se mide por puntos, como si estuvieses en un juego. No se mide por la cantidad de amigos ni por c\u00f3mo te miran o te aceptan los dem\u00e1s. No se mide seg\u00fan los planes que tengas para el fin de semana. Tampoco seg\u00fan con qui\u00e9n sal\u00eds, con quien saliste [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3920,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[380,379],"class_list":["post-3908","post","type-post","status-publish","format-standard","has-post-thumbnail","category-de-puno-y-letra","tag-amistad","tag-sergio-lapegue-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo se mide la vida? - Sergio Lapegue<\/title>\n<meta name=\"description\" content=\"Solo vos eleg\u00eds la manera en la que vas a afectar la vida de otras personas. La vida se mide con los compromisos que uno cumple. \u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo se mide la vida? - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"Solo vos eleg\u00eds la manera en la que vas a afectar la vida de otras personas. La vida se mide con los compromisos que uno cumple. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-04T19:07:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-04T19:07:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2022\/04\/277615733_261702726170170_1133272757134253300_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sergio Lapegue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sergiolapegue\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Lapegue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/\"},\"author\":{\"name\":\"Sergio Lapegue\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"headline\":\"\u00bfC\u00f3mo se mide la vida?\",\"datePublished\":\"2022-04-04T19:07:10+00:00\",\"dateModified\":\"2022-04-04T19:07:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/\"},\"wordCount\":329,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/277615733_261702726170170_1133272757134253300_n.jpg\",\"keywords\":[\"amistad\",\"Sergio Lapeg\u00fce\"],\"articleSection\":[\"De Pu\u00f1o y Letra\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/\",\"name\":\"\u00bfC\u00f3mo se mide la vida? - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/277615733_261702726170170_1133272757134253300_n.jpg\",\"datePublished\":\"2022-04-04T19:07:10+00:00\",\"dateModified\":\"2022-04-04T19:07:11+00:00\",\"description\":\"Solo vos eleg\u00eds la manera en la que vas a afectar la vida de otras personas. La vida se mide con los compromisos que uno cumple. \u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/277615733_261702726170170_1133272757134253300_n.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/277615733_261702726170170_1133272757134253300_n.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2022\\\/04\\\/04\\\/como-se-mide-la-vida-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo se mide la vida?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/sergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo se mide la vida? - Sergio Lapegue","description":"Solo vos eleg\u00eds la manera en la que vas a afectar la vida de otras personas. La vida se mide con los compromisos que uno cumple. \u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo se mide la vida? - Sergio Lapegue","og_description":"Solo vos eleg\u00eds la manera en la que vas a afectar la vida de otras personas. La vida se mide con los compromisos que uno cumple. \u00a0","og_url":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2022-04-04T19:07:10+00:00","article_modified_time":"2022-04-04T19:07:11+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2022\/04\/277615733_261702726170170_1133272757134253300_n.jpg","type":"image\/jpeg"}],"author":"Sergio Lapegue","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sergiolapegue","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Sergio Lapegue","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/"},"author":{"name":"Sergio Lapegue","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"headline":"\u00bfC\u00f3mo se mide la vida?","datePublished":"2022-04-04T19:07:10+00:00","dateModified":"2022-04-04T19:07:11+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/"},"wordCount":329,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2022\/04\/277615733_261702726170170_1133272757134253300_n.jpg","keywords":["amistad","Sergio Lapeg\u00fce"],"articleSection":["De Pu\u00f1o y Letra"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/","url":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/","name":"\u00bfC\u00f3mo se mide la vida? - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2022\/04\/277615733_261702726170170_1133272757134253300_n.jpg","datePublished":"2022-04-04T19:07:10+00:00","dateModified":"2022-04-04T19:07:11+00:00","description":"Solo vos eleg\u00eds la manera en la que vas a afectar la vida de otras personas. La vida se mide con los compromisos que uno cumple. \u00a0","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2022\/04\/277615733_261702726170170_1133272757134253300_n.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2022\/04\/277615733_261702726170170_1133272757134253300_n.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2022\/04\/04\/como-se-mide-la-vida-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo se mide la vida?"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"],"url":"https:\/\/sergiolapegue.com\/site\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/3908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=3908"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/3908\/revisions"}],"predecessor-version":[{"id":3921,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/3908\/revisions\/3921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/3920"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=3908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=3908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=3908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}