{"id":24863,"date":"2025-08-22T17:00:00","date_gmt":"2025-08-22T20:00:00","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=24863"},"modified":"2025-08-21T17:51:50","modified_gmt":"2025-08-21T20:51:50","slug":"se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/","title":{"rendered":"SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Asociaci\u00f3n Civil Premios Hugo&nbsp;anuncia las nominaciones de&nbsp;la 15\u00aa edici\u00f3n de este prestigioso galard\u00f3n, que distingue lo mejor de la actividad del teatro musical en nuestro pa\u00eds. Creados por&nbsp;Ricky Pashkus y Pablo Gorlero, los Premios Hugo celebran el talento, la creatividad y la excelencia de las producciones y artistas que enriquecen el g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta edici\u00f3n especial, adem\u00e1s de las categor\u00edas habituales, se entregar\u00e1 el&nbsp;Premio Hugo de Oro, un reconocimiento que se otorga cada cinco a\u00f1os para destacar una contribuci\u00f3n excepcional al teatro musical. Este galard\u00f3n resalta el impacto y la trayectoria de figuras o producciones que han marcado un hito en la escena cultural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las obras m\u00e1s nominadas se encuentran:&nbsp;La revista del Cervantes &nbsp; &nbsp;(18 nominaciones), La sirenita con (17), Despertar de primavera (16), Sandro, el gran show (14), Derecho de piso (13), Sapos secos (9), El barbero de Sevilla (9), Saraos Uranistas (8), La Ratoncita P\u00e9rez (7), Cuentopos de Gulub\u00fa (6), K\u00fcy\u00e9n Huapi (6), Mina che cosa sei? (5), El fado de Ulises (5), Alicia, Alice by heart (4), Coraza c\u00e1scara casa (4), Pretty Woman (3), Liza y Orson, una historia entre mandarinas (3).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se premiar\u00e1n las propuestas del g\u00e9nero gestadas en diferentes regiones del pa\u00eds en el segmento Premios Hugo Federales, que incluye producciones de ciudades como C\u00f3rdoba, Gran Buenos Aires, La Plata, Mendoza, Mar del Plata, Rosario, Bah\u00eda Blanca, Tucum\u00e1n y San Juan, destacando la riqueza y diversidad del teatro musical en todo el territorio nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Ceremonia de Entrega de Diplomas a los nominados se llevar\u00e1 a cabo el lunes 1 de septiembre a las 18:00 horas en el emblem\u00e1tico Teatro Liceo.&nbsp;En las pr\u00f3ximas semanas se confirmar\u00e1 la fecha y lugar donde se realice la Ceremonia de Premiaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta 15\u00aa edici\u00f3n de los Premios Hugo cuenta con el valioso apoyo de la Fundaci\u00f3n Santander Argentina, para reafirmar el compromiso de Santander con la cultura, el arte y la educaci\u00f3n del pa\u00eds a trav\u00e9s de Mecenazgo Cultural, el programa del Ministerio de Cultura de la Ciudad, que impulsa proyectos art\u00edsticos-culturales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para m\u00e1s informaci\u00f3n sobre las nominaciones y la ceremonia, visite su p\u00e1gina web:&nbsp;<a href=\"https:\/\/tpagencia.tr.pemsv18.net\/c\/eyJhIjoidHBhZ2VuY2lhIiwibSI6Im1haWxfY21lZDFucjlsMXRpOTA4MTRscjZ1NHI5OSIsImwiOiJsaW5rXzRlOWJhNWM0NTZkZTZmYTJmOTk3MWJhMGZhZjM0MDM5ZWRmZmRhYWVfNmE2NzA0IiwiaSI6W10sInUiOiJodHRwczovL3d3dy5wcmVtaW9zaHVnby5vcmcuYXI_dXRtX3NvdXJjZT1wZXJmaXQmdXRtX21lZGl1bT1lbWFpbCZ1dG1fY2FtcGFpZ249UHJlbWlvcyUyMEh1Z28lMjAyMDI1IiwiYyI6IiIsImgiOiIyYmFmMDAifQ\" target=\"_blank\" rel=\"noreferrer noopener\">www.premioshugo.org.ar<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"451\" height=\"149\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-2.png\" alt=\"\" class=\"wp-image-24865\" style=\"width:696px;height:auto\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-2.png 451w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-2-300x99.png 300w\" sizes=\"auto, (max-width: 451px) 100vw, 451px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre los Premios Hugo al Teatro Musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Premios Hugo son una iniciativa creada por Ricky Pashkus y Pablo Gorlero con el fin de distinguir todos los rubros, categor\u00edas y especializaciones del teatro musical en nuestro pa\u00eds. Han tomado el nombre de Hugo Mid\u00f3n como un modelo a seguir y homenaje en vida a uno de los maestros m\u00e1s importantes del g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Asociaci\u00f3n Civil Premios Hugo se propone estimular toda forma de teatro musical y todas las expresiones art\u00edsticas y\/o t\u00e9cnicas inherentes al mismo. Adem\u00e1s del est\u00edmulo a trav\u00e9s de una premiaci\u00f3n anual, se busca fomentar y gestar procesos de formaci\u00f3n as\u00ed como de perfeccionamiento profesional o de inserci\u00f3n laboral.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/tpagencia.tr.pemsv18.net\/c\/eyJhIjoidHBhZ2VuY2lhIiwibSI6Im1haWxfY21lZDFucjlsMXRpOTA4MTRscjZ1NHI5OSIsImwiOiJsaW5rXzQzMGFkYTc2NGI0MjI2NzM1YWVkMWZiYWQxYWYxZjA3Y2I0MWEyMjFfOWM5NzZjIiwiaSI6W10sInUiOiJodHRwczovL3d3dy5pbnN0YWdyYW0uY29tL3ByZW1pb3NodWdvP3V0bV9zb3VyY2U9cGVyZml0JnV0bV9tZWRpdW09ZW1haWwmdXRtX2NhbXBhaWduPVByZW1pb3MlMjBIdWdvJTIwMjAyNSIsImMiOiIiLCJoIjoiNzFhYzk0In0\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>INSTAGRAM OFICIAL<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acerca de Fundaci\u00f3n Santander Argentina<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3n Santander Argentina abri\u00f3 sus puertas en julio de 2019 para reafirmar el compromiso de Santander con la cultura, el arte y la educaci\u00f3n del pa\u00eds. Desde la intersecci\u00f3n de las avenidas Juan de Garay y Paseo Col\u00f3n, en el denominado Distrito de las Artes de la ciudad de Buenos Aires, el objetivo de la Fundaci\u00f3n es contribuir al desarrollo y la difusi\u00f3n de la cultura, con especial foco en la promoci\u00f3n del arte contempor\u00e1neo.<br>Acompa\u00f1ando al programa anual de exposiciones, se desarrollan visitas educativas, charlas, seminarios y talleres de formaci\u00f3n art\u00edstica. Adem\u00e1s, la Fundaci\u00f3n Santander Argentina difunde y brinda apoyo al coleccionismo y a la producci\u00f3n art\u00edstica a trav\u00e9s de distintas iniciativas en conjunto con Santander y\/u otras instituciones culturales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acerca de la Banca Responsable \/ ESG de Santander Argentina<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El compromiso de Santander Argentina es contribuir al progreso de las personas y las empresas, impulsando el crecimiento inclusivo y sostenible. Por ello, llevamos adelante diversas iniciativas sociales, ambientales y de gobernanza para generar triple impacto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el 2021, m\u00e1s de 230 mil personas recibieron el apoyo de Santander, a trav\u00e9s de diversos programas enfocados en la comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contamos con 60 emprendimientos de impacto social y ambiental en el programa SuperClub+ Comprometidos, impulsando el consumo responsable y el emprendedurismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n impulsamos iniciativas para reducir el impacto ambiental: somos neutros en carbono y llevamos adelante programas de reducci\u00f3n de la misma, vinculadas a eficiencia energ\u00e9tica y alianzas ambientales. Estamos transformando nuestros espacios, contamos con Sucursales Sustentables, donde se aplica tecnolog\u00eda sostenible a trav\u00e9s del uso de energ\u00eda solar y un sistema de ahorro energ\u00e9tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Empujamos las finanzas sostenibles: contamos con l\u00edneas de financiaci\u00f3n para personas y pymes, destinadas a productos sustentables y a proyectos de desarrollo sostenible. Acompa\u00f1amos a nuestros clientes en su transici\u00f3n hacia una econom\u00eda baja en carbono: somos colocadores del primer Bono Sostenible para Plaza Log\u00edstica, el primer Bono linkeado a la Sostenibilidad con San Miguel, y el primer Bono Social para una ONG.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para conocer m\u00e1s sobre el Compromiso Santander ingresa a su p\u00e1gina web: &nbsp;<a href=\"https:\/\/tpagencia.tr.pemsv18.net\/c\/eyJhIjoidHBhZ2VuY2lhIiwibSI6Im1haWxfY21lZDFucjlsMXRpOTA4MTRscjZ1NHI5OSIsImwiOiJsaW5rXzgzMWFiODk2YjdjOWFiYzU4Y2I2Zjk5YTdlNjM5NjRiZTQ4ODc1NmZfMzJkYmZmIiwiaSI6W10sInUiOiJodHRwczovL3d3dy5zYW50YW5kZXIuY29tLmFyL2NvbXByb21pc29zYW50YW5kZXI_dXRtX3NvdXJjZT1wZXJmaXQmdXRtX21lZGl1bT1lbWFpbCZ1dG1fY2FtcGFpZ249UHJlbWlvcyUyMEh1Z28lMjAyMDI1IiwiYyI6IiIsImgiOiI1ZGJmNjgifQ\" target=\"_blank\" rel=\"noreferrer noopener\">www.santander.com.ar\/compromisosantander<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1004\" height=\"1024\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-1-1004x1024.jpg\" alt=\"\" class=\"wp-image-24864\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-1-1004x1024.jpg 1004w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-1-294x300.jpg 294w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-1-768x783.jpg 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-1-412x420.jpg 412w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-1-696x710.jpg 696w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-1-1068x1089.jpg 1068w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025-1.jpg 1404w\" sizes=\"auto, (max-width: 1004px) 100vw, 1004px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Per\u00edodo del 01\/08\/2024 hasta el 31\/07\/2025<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1 \u2013 MEJOR MUSICAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despertar de primavera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La revista del Cervantes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sirenita<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2 \u2013 MEJOR MUSIC HALL, CAF\u00c9 CONCERT Y\/O VARIET\u00c9 MUSICAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Disney celebra: Una Navidad Inolvidable<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laboratorio de amor<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mina che cosa sei?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sandro, el gran show<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3 \u2013 MEJOR MUSICAL OFF<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derecho de piso<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sapos Secos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saraos uranistas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4 \u2013 MEJOR DIRECCI\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Sans &#8211; Julio Panno (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ariel del Mastro &#8211; Marcelo Caballero (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fer Dente (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pablo Maritano (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5 \u2013 MEJOR COREOGRAF\u00cdA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andrea Servera (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anal\u00eda Gonz\u00e1lez (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vanesa Garc\u00eda Mill\u00e1n (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ver\u00f3nica Pecollo (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6 \u2013 MEJOR DIRECCI\u00d3N MUSICAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fernando Albinarrate (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gaby Goldman (Mina che cosa sei?)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ian Shifres (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 Luis Pag\u00e1n (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sebasti\u00e1n Aldea D\u00e1vila (Sapos secos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7 \u2013 MEJOR LIBRO DE MUSICAL ARGENTINO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Schimelman &#8211; Ian Shifres (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juanse Rausch (Saraos Uranistas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pedro Vel\u00e1zquez (Sapos secos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>8 \u2013 MEJORES LETRAS DE MUSICAL ARGENTINO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gabo Illanes &#8211; Juanse Rausch (Saraos Uranistas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ian Shifres (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pedro Vel\u00e1zquez (Sapos secos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vanesa Butera (Coraza c\u00e1scara casa)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>9 \u2013 MEJOR ADAPTACI\u00d3N Y\/O TRADUCCI\u00d3N DE LIBRO Y LETRAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Julio Panno &#8211; Ro Noziglia (Alicia, Alice by heart)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marcelo Caballero &#8211; Juan Pablo Schapira (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marcelo Kotliar (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10 &#8211; MEJOR M\u00daSICA ORIGINAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gabo Illanes (Saraos Uranistas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ian Shifres (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sebasti\u00e1n Aldea D\u00e1vila (Sapos secos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vanesa Butera (Coraza c\u00e1scara casa)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>11 \u2013 MEJORES ARREGLOS MUSICALES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enzo Ferrari (Laboratorio de amor)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fernando Albinarrate &#8211; Gerardo Delgado (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 Luis Pagan (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>12 \u2013 MEJOR ACTUACI\u00d3N PROTAG\u00d3NICA MASCULINA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marco Antonio Caponi (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sebasti\u00e1n Su\u00f1\u00e9 (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valent\u00edn Zaninelli (Alicia, Alice by heart)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>13 \u2013 MEJOR ACTUACI\u00d3N PROTAG\u00d3NICA FEMENINA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agostina Becco (Alicia, Alice by heart)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Florencia Pe\u00f1a (Pretty woman)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Rosa Fugazot (El porvenir)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trini Montiel (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>14 \u2013 MEJOR ACTUACI\u00d3N MASCULINA EN MUSIC HALL, CAF\u00c9 CONCERT y\/o VARIET\u00c9 MUSICAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alan Madanes (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diego Reinhold (Mina che cosa sei?)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nacho P\u00e9rez Cortez (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>15 \u2013 MEJOR ACTUACI\u00d3N FEMENINA EN MUSIC HALL, CAF\u00c9 CONCERT y\/o VARIET\u00c9 MUSICAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elena Roger (Mina che cosa sei?)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malena Rossi (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sof\u00eda Val (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>16 \u2013 MEJOR ACTUACI\u00d3N DE REPARTO MASCULINA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joaqu\u00edn Scotta (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 Mar\u00eda Listorti (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mariano Magnifico (Pretty Woman)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nahuel Adhami (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tom\u00e1s Wicz (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>17 \u2013 MEJOR ACTUACI\u00d3N DE REPARTO FEMENINA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alejandra Radano (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Evelyn Botto (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00cdride Mockert (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jessica Abouchain (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paz Gutierrez (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>18 &#8211; MEJOR INTERPRETACI\u00d3N MASCULINA EN ENSAMBLE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gonzalo Gerber (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guido Savino (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juli\u00e1n Rubino (Alicia, Alice by heart)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lare (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sacha Bercovich (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>19 \u2013 MEJOR INTERPRETACI\u00d3N FEMENINA EN ENSAMBLE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noelia Vera (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ro Noziglia (Pretty woman)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valentina Pergolini (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>20 \u2013 MEJOR DIRECCI\u00d3N VOCAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eugenia Gil Rodr\u00edguez (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fernando Albinarrate (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ian Shifres (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sebasti\u00e1n Mazzoni (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>21 \u2013 MEJOR PRODUCCI\u00d3N INTEGRAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ozono-MP-Los Rottenberg (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sandro Producciones &#8211; 3C Films &#8211; JLP Music &#8211; Torneos (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Teatro Nacional Cervantes (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>22 \u2013 REVELACI\u00d3N MASCULINA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gerardo Chendo (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jer\u00f3nimo Giocondo Bosia (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicol\u00e1s Sousa (Sapos secos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Octavio Murillo (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>23 \u2013 REVELACI\u00d3N FEMENINA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Albana Fuentes (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guadalupe Otheguy (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Monina Bonelli (La Diabla o c\u00f3mo destruir el mundo)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>24 \u2013 MEJOR DISE\u00d1O DE VESTUARIO ORIGINAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Sans (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Polilla (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Emilia Tambutti (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Romina Lanzillotta &#8211; Catalina Rodr\u00edguez Loredo (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>25 \u2013 MEJOR ESCENOGRAF\u00cdA Y\/O DISE\u00d1O AUDIOVISUAL ORIGINAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andrea Mercado (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gonzalo C\u00f3rdoba Est\u00e9vez (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jorge Ferrari &#8211; Maxi Vecco (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>26 &#8211; MEJOR CARACTERIZACI\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adam Efron (maquillaje de Saraos Uranistas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Emilia Tambutti (maquillaje de La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mat\u00edas Nazareno (maquillaje de La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>27 \u2013 MEJOR DISE\u00d1O DE LUCES ORIGINAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anteo del Mastro &#8211; Sebasti\u00e1n Viola (La sirenita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leo Mu\u00f1oz &#8211; Julio Panno (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lucas Gabriel Gringas (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sebasti\u00e1n Francia (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ver\u00f3nica Alcoba (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>28 \u2013 MEJOR DISE\u00d1O DE SONIDO ORIGINAL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ariel Gato &#8211; Camilo Zentner (La revista del Cervantes)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eugenio Mellano Lanfranco &#8211; Luciano Ricardi (Sandro, el gran show)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gast\u00f3n Briski (Despertar de primavera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rodrigo Lavecchia (Mina che cosa sei?)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>29 \u2013 MEJOR ESPECT\u00c1CULO MUSICAL PARA UN SOLO INT\u00c9RPRETE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coraza c\u00e1scara casa (Vanesa Butera)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Diabla o c\u00f3mo destruir el mundo (Monina Bonelli)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi vida anterior (Dennis Smith)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>30 \u2013 MEJOR DIRECCI\u00d3N EN MUSICAL OFF<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Schimelman &#8211; Ian Shifres (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dennis Smith (Mi vida anterior)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juanse Rausch (Saraos Uranistas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pedro Vel\u00e1zquez (Sapos secos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sebasti\u00e1n Su\u00f1\u00e9 (Coraza c\u00e1scara casa)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>31 \u2013 MEJOR INTERPRETACI\u00d3N MASCULINA EN MUSICAL OFF<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nacho de Santis (Sapos secos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicol\u00e1s Mart\u00edn (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Omar Lopardo (Opereta de los bandoleros)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tom\u00e1s Wicz (Saraos Uranistas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>32 &#8211; MEJOR INTERPRETACI\u00d3N FEMENINA EN MUSICAL OFF<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lucre Orlando (Sapos secos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luc\u00eda Ad\u00fariz Bravo (Saraos Uranistas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Victoria Baldomir (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vero Gerez (Derecho de piso)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>33 &#8211; MEJOR MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuentopos de Gulub\u00fa<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El barbero de Sevilla<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fado de Ulises<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Ratoncita P\u00e9rez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>34 &#8211; MEJOR DIRECCI\u00d3N EN MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claudio Hochman (El fado de Ulises)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e9ctor Presa (La Ratoncita P\u00e9rez)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Jaunarena (El barbero de Sevilla)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>35 &#8211; MEJOR COREOGRAF\u00cdA EN MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ariel Pastocchi &#8211; Mat\u00edas Prieto Peccia (K\u00fcy\u00e9n Huapi)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marina Svartzman (Cuentopos de Gulub\u00fa)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>36 &#8211; MEJOR LIBRO EN MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claudio Hochman (El fado de Ulises)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e9ctor Presa (La Ratoncita P\u00e9rez)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Jaunarena (El barbero de Sevilla)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pablo Di Felice (Liza y Orson, una historia entre mandarinas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>37 &#8211; MEJORES LETRAS EN MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claudio Hochman (El fado de Ulises)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Jaunarena (El barbero de Sevilla)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mat\u00edas Prieto Peccia (K\u00fcy\u00e9n Huapi)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>38 &#8211; MEJOR M\u00daSICA ORIGINAL DE MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diego Lozano (La Ratoncita P\u00e9rez)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diego Lozano (Liza y Orson, una historia entre mandarinas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fran Gaia &#8211; Sol Bardi (K\u00fcy\u00e9n Huapi)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hern\u00e1n Matorra (El pulpo est\u00e1 crudo)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>39 &#8211; MEJOR INTERPRETACI\u00d3N FEMENINA EN MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carlota Blanc (El fado de Ulises)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laura Penchi (El barbero de Sevilla)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luli Romano Lastra (La Ratoncita P\u00e9rez)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabrina Lara (Dafne y el drag\u00f3n)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valeria Acciaresi (La Ratoncita P\u00e9rez)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>40 &#8211; MEJOR INTERPRETACI\u00d3N MASCULINA EN MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Emiliano Pi \u00c1lvarez (Cuentopos de Gulub\u00fa)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gabriel Carasso (El barbero de Sevilla)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pablo Di Felice (Liza y Orson, una historia entre mandarinas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>41 &#8211; MEJOR PRODUCCI\u00d3N EN MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ariel Ciocco (La Historia sin fin)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Galaxias Creativas (Cuentopos de Gulub\u00fa)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gustavo Passerino (El barbero de Sevilla)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noeli Chiarenza (K\u00fcy\u00e9n Huapi)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>42 &#8211; MEJOR DISE\u00d1O DE ESCENOGRAF\u00cdA EN MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00e9sar Berguella (K\u00fcy\u00e9n Huapi)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gonzalo C\u00f3rdova Est\u00e9vez (El barbero de Sevilla)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e9ctor Presa &#8211; Claudio Provenzano (La Ratoncita P\u00e9rez)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marcelo Valiente (Cuentopos de Gulub\u00fa)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>43 &#8211; MEJOR DISE\u00d1O DE VESTUARIO EN MUSICAL INFANTIL Y\/O JUVENIL<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Jaunarena (El barbero de Sevilla)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noeli Chiarenza &#8211; Roberto S\u00e1nchez &#8211; Fabiana Marlo (K\u00fcy\u00e9n Huapi)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sandra Szwarcberg &#8211; Flavia Pereda (Cuentopos de Gulub\u00fa)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NOMINACIONES PREMIOS HUGO FEDERALES 2025<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1 \u2013 SEDE SAN JUAN<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor direcci\u00f3n en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sonia Belmonte (Demonios)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n femenina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agostina Ramella (Basta ya)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Luz Correa (Demonios)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ana Luz Torras (Demonios)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luna Herrera (Deolinda)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paula Torres (Demonios)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yuliana Guevara (Deolinda)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n masculina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Federico Sosa (Un loco experimento)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fernando D\u00edaz (Demonios)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gabriel Navarro (Deolinda)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ignacio Est\u00e9vez (Deolinda)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor libro y\/o letras<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Federico Sosa (Un loco experimento)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pablo Flores Torres &amp; Ces\u00e1reo Alfonso Garc\u00eda (Deolinda)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sonia Belmonte &amp; Leo Bosio (Demonios)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor m\u00fasica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pablo Flores Torres (Deolinda)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Basta ya<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Demonios<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deolinda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un loco experimento<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2 \u2013 SEDE ROSARIO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor direcci\u00f3n en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ceffarelli Nicolas (Pintando a Berni)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Clara Saavedra \u2013 Juan Ormaechea \u2013 Sofia Monge (A partir de ahora)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lucas Masan (Transformadas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manuel Cansino (Por siempre rock nacional)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n femenina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lucia Ordo\u00f1ez (A partir de ahora)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marcela Serriccio (Circus, el musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Soledad Galv\u00e1n (OTA)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paula Vallone (Familia sustantivo femenino)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Romina Casella (Familia sustantivo femenino)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n masculina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e9ctor Ansaldi (Piripincho geneal\u00f3gico)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leandro Rojas (Familia sustantivo femenino)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marcos Franchin (Transformadas)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santiago Pereiro (OTA)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor libro y\/o letras<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Florencia Cresto (Pintando a Berni)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e9ctor Ansaldi, Benjam\u00edn Ansaldi, Fausto Ansaldi (Piripincho geneal\u00f3gico)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicolas Dilorenzo (Historias de amor y m\u00e1s o menos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pablo Silvestri, Pablo Locatelli, Giorgio Marianela, Neve Agust\u00edn (Hechos, una historia diferente)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor m\u00fasica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicolas Dilorenzo (Historias de amor y m\u00e1s o menos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pablo Silvestri, Pablo Locatelli, Todino Cristian, Chamorro Mauricio, Cutuli Ramiro (Hechos, una historia diferente)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de ahora<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Circus<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Familia sustantivo femenino<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hechos, una historia diferente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Historias de amor y m\u00e1s o menos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">OTA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Transformadas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3 \u2013 SEDE MENDOZA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor direcci\u00f3n en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Federico Ortega (Hizo falta tanta agua)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hugo Moreno (La casa de al lado)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n femenina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 Canillas (Hizo falta tanta agua)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Natalia Polo (Hizo falta tanta agua)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n masculina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">David P\u00e1ez (Modo Avi\u00f3n)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gianfranco Dimattia (La casa de al lado)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Migue Calder\u00f3n (Hizo falta tanta agua)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor libro y\/o letras<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lautaro Volpe (Hizo falta tanta agua)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor m\u00fasica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fernando \u00c1lvarez (La casa de al lado)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pablo Orellano (Hizo falta tanta agua)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hizo falta tanta agua<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La casa de al lado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4 \u2013 SEDE MAR DEL PLATA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor direcci\u00f3n en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leo Rizzi (La Vargas, un musical de Chavela)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mariano Magnifico (Fanfarria de Vox Popurr\u00ed)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mat\u00edas Minue (Un mundo de dulzura)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n femenina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agustina Bericiartua (Un mundo de dulzura)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coral Embon (Voces del musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Karina Levine (La Vargas, un musical de Chavela)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lucia Rodr\u00edguez (Voces del musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Macarena Paggi (Mi princesa busca un zapatito)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mona de Marco (La Vargas, un musical de Chavela)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n masculina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carlos de Pratti (Piyamada en Halloween)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nahuel Sacco (Voces del musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ramiro Barriga (Voces del musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor libro y\/o letras<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carlo Peton (Mi princesa busca un zapatito)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Giuliana Olarticoechea (Invasi\u00f3n m\u00e1gica)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C. Suero, I. Corva y M. Magnifico (Fanfarria de Vox Popurr\u00ed)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leo Rizzi (La Vargas, un musical de Chavela)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mat\u00edas Minue (Mundo de dulzura)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor m\u00fasica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denise Cerrone y G. Calabrese (Mundo de dulzura)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ignacio Corva y Camila Suero (Fanfarria de Vox Popurr\u00ed)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Carreras y A. Davin (Piyamada en Halloween)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Victoria Cano y G. Olarticoechea (Invasi\u00f3n m\u00e1gica)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fanfarria de Vox Popurr\u00ed<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Vargas, un musical de Chavela<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un mundo de dulzura<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5 \u2013 SEDE LA PLATA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor direcci\u00f3n en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorena Vel\u00e1zquez (Felicitas, el fantasma m\u00e1s bello de la Rep\u00fablica)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Pascual (Fiumiccino)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n femenina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Micaela Pereyra (Fiumiccino)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paula Barbi (Superluz. Una nueva aventura)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sol Bordeu (Felicitas, el fantasma m\u00e1s bello de la Rep\u00fablica)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n masculina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facundo Olivera (Fiumiccino)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facundo V\u00e9lez (Fiumiccino)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santiago Dana (Felicitas, el fantasma m\u00e1s bello de la Rep\u00fablica)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor libro y\/o letras<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorena Vel\u00e1zquez (Felicitas, el fantasma m\u00e1s bello de la Rep\u00fablica)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Pascual (Fiumiccino)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor m\u00fasica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juan F\u00e9lix Pissinis (Felicitas, el fantasma m\u00e1s bello de la Rep\u00fablica)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sergio Perotti (Alicia y su mundo de ensue\u00f1o)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tom\u00e1s Barrios y Gonzalo Fantoni (Fiumiccino)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Felicitas, el fantasma m\u00e1s bello de la Rep\u00fablica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fiumiccino &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>6 \u2013 SEDE GRAN BUENOS AIRES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor direcci\u00f3n en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Devora Sa y Fernando Ursino (Mam\u00e1 esta m\u00e1s chiquita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marisela Baima (Oz, un viaje encantado)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sergio Lombardo (Stranger Sings)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n femenina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Andrea Koczan (Oz un viaje encantado)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cecilia Dibur (Mam\u00e1 esta m\u00e1s chiquita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guadalupe Olguin (Stranger Sings)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Victoria Ponte (Stranger Sings)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n masculina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facu Pola (Mam\u00e1 esta m\u00e1s chiquita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Felipe Alonso (Stranger Sings)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mart\u00edn Erhardt (Stranger Sings)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e9stor Barrios (Oz un viaje encantado)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor libro y\/o letras<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Florencia C\u00e1ceres (Oz, un viaje encantado)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ignacio Olivera (Mam\u00e1 esta m\u00e1s chiquita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jonathan Hogue y Sergio Lombardo (Stranger Sings)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor m\u00fasica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jonathan Hogue y Sergio Lombardo (Stranger Sings)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Pablo Schapiro (Mam\u00e1 esta m\u00e1s chiquita)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e9stor Coco (Oz, un viaje encantado)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mam\u00e1 esta m\u00e1s chiquita<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oz, un viaje encantado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stranger Sings<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>7 \u2013 SEDE C\u00d3RDOBA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor direcci\u00f3n en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alejandro Issidoros y Luciana Sgr\u00f3 Ruata (Yiya, el musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lara Jord\u00e1n Cruz (Brochero en esencia, el musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n femenina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alejandra Mart\u00ednez (Ouija, un musical del m\u00e1s all\u00e1)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Charlie Cabalieri (Noche de terror)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laura Ortiz (Yiya, el musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Paz Flores) (La pelada de la ca\u00f1ada)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor interpretaci\u00f3n masculina en espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gabriel Cambiasso (Yiya, el musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Germ\u00e1n Molina (Brochero en esencia, el musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nelson Balmaceda (Yiya, el musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor libro y\/o letras<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fernando Rahe (Simplemente Gina)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lara Jord\u00e1n Cruz (Brochero en esencia, el musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor m\u00fasica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Emmanuel Mill\u00e1n (La pelada de la ca\u00f1ada, un thriller musical)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fernando Rahe (Simplemente Gina)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mejor espect\u00e1culo musical<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brochero en esencia, el musical<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yiya, el musical<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias Tommy Pashkus Agencia por acercarnos las nominaciones de los Premios Hugo 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n Civil Premios Hugo&nbsp;anuncia las nominaciones de&nbsp;la 15\u00aa edici\u00f3n de este prestigioso galard\u00f3n, que distingue lo mejor de la actividad del teatro musical en nuestro pa\u00eds. Creados por&nbsp;Ricky Pashkus y Pablo Gorlero, los Premios Hugo celebran el talento, la creatividad y la excelencia de las producciones y artistas que enriquecen el g\u00e9nero. En esta [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":24866,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,35],"tags":[],"class_list":["post-24863","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arte","category-teatro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL - Sergio Lapegue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"La Asociaci\u00f3n Civil Premios Hugo&nbsp;anuncia las nominaciones de&nbsp;la 15\u00aa edici\u00f3n de este prestigioso galard\u00f3n, que distingue lo mejor de la actividad del teatro musical en nuestro pa\u00eds. Creados por&nbsp;Ricky Pashkus y Pablo Gorlero, los Premios Hugo celebran el talento, la creatividad y la excelencia de las producciones y artistas que enriquecen el g\u00e9nero. En esta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/danielernesto.montana\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-22T20:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel E. Monta\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/daner_004\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel E. Monta\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/\"},\"author\":{\"name\":\"Daniel E. Monta\u00f1a\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/9198e7dbab43c6d74d0fd5399af7c3cd\"},\"headline\":\"SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL\",\"datePublished\":\"2025-08-22T20:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/\"},\"wordCount\":3296,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Premios-Hugo-2025.jpg\",\"articleSection\":[\"Arte\",\"Teatro\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/\",\"name\":\"SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Premios-Hugo-2025.jpg\",\"datePublished\":\"2025-08-22T20:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Premios-Hugo-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Premios-Hugo-2025.jpg\",\"width\":1440,\"height\":1421},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/22\\\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/9198e7dbab43c6d74d0fd5399af7c3cd\",\"name\":\"Daniel E. Monta\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"caption\":\"Daniel E. Monta\u00f1a\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/danielernesto.montana\",\"https:\\\/\\\/instagram.com\\\/daniel_montana1961\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/daner_004\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/daniel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL - Sergio Lapegue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/","og_locale":"es_ES","og_type":"article","og_title":"SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL - Sergio Lapegue","og_description":"La Asociaci\u00f3n Civil Premios Hugo&nbsp;anuncia las nominaciones de&nbsp;la 15\u00aa edici\u00f3n de este prestigioso galard\u00f3n, que distingue lo mejor de la actividad del teatro musical en nuestro pa\u00eds. Creados por&nbsp;Ricky Pashkus y Pablo Gorlero, los Premios Hugo celebran el talento, la creatividad y la excelencia de las producciones y artistas que enriquecen el g\u00e9nero. En esta [&hellip;]","og_url":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/danielernesto.montana","article_published_time":"2025-08-22T20:00:00+00:00","og_image":[{"width":1440,"height":1421,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025.jpg","type":"image\/jpeg"}],"author":"Daniel E. Monta\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/daner_004","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Daniel E. Monta\u00f1a","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/"},"author":{"name":"Daniel E. Monta\u00f1a","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/9198e7dbab43c6d74d0fd5399af7c3cd"},"headline":"SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL","datePublished":"2025-08-22T20:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/"},"wordCount":3296,"commentCount":0,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025.jpg","articleSection":["Arte","Teatro"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/","url":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/","name":"SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025.jpg","datePublished":"2025-08-22T20:00:00+00:00","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/Premios-Hugo-2025.jpg","width":1440,"height":1421},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/22\/se-dieron-a-conocer-las-nominaciones-de-la-15-edicion-de-los-premios-hugo-2025-al-teatro-musical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"SE DIERON A CONOCER LAS NOMINACIONES DE LA 15\u00b0 EDICI\u00d3N DE LOS PREMIOS HUGO 2025 AL TEATRO MUSICAL"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"]},{"@type":"Person","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/9198e7dbab43c6d74d0fd5399af7c3cd","name":"Daniel E. Monta\u00f1a","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","caption":"Daniel E. Monta\u00f1a"},"sameAs":["https:\/\/facebook.com\/danielernesto.montana","https:\/\/instagram.com\/daniel_montana1961","https:\/\/x.com\/https:\/\/twitter.com\/daner_004"],"url":"https:\/\/sergiolapegue.com\/site\/author\/daniel\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/24863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=24863"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/24863\/revisions"}],"predecessor-version":[{"id":24867,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/24863\/revisions\/24867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/24866"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=24863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=24863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=24863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}