{"id":24539,"date":"2025-08-03T13:00:00","date_gmt":"2025-08-03T16:00:00","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=24539"},"modified":"2025-08-02T01:17:53","modified_gmt":"2025-08-02T04:17:53","slug":"el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/","title":{"rendered":"EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El reconocido m\u00e9dico cl\u00ednico especialista en Medicina Interna y Gastroenterolog\u00eda (MN 94517), autor best-seller,&nbsp;Dr. Facundo Pereyra, luego de haber presentado su libro Agotados en varios teatros con \u00e9xito,&nbsp;vuelve por cuarta vez a la Sala Picasso del Paseo La Plaza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cita ser\u00e1 el pr\u00f3ximo Lunes 11 de agosto a las 20:00 horas. Donde se abordar\u00e1 el tema del cansancio con un enfoque integral que combina ciencia, nutrici\u00f3n y bienestar emocional.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"755\" height=\"1024\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-3.jpg\" alt=\"\" class=\"wp-image-24543\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-3.jpg 755w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-3-221x300.jpg 221w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-3-310x420.jpg 310w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-3-696x944.jpg 696w\" sizes=\"auto, (max-width: 755px) 100vw, 755px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el Dr. Facundo Pereyra ser\u00e1 parte por primera vez del evento 8\u00aa versi\u00f3n del MCAFESTIVAL 2025;&nbsp; Mente Cuerpo Alma (<a href=\"https:\/\/www.mcafestival.com\/\">https:\/\/www.mcafestival.com\/<\/a>) en Chile. Es el encuentro m\u00e1s influyente de Latinoam\u00e9rica en bienestar, conciencia y transformaci\u00f3n humana. Se desarrollar\u00e1 los d\u00edas 22, 23 y 24 de agosto. El Dr. Facundo Pereyra estar\u00e1 los d\u00edas s\u00e1bado 23 y domingo 24 de agosto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;Dr. Facundo Pereyra, m\u00e9dico cl\u00ednico especialista en Medicina Interna y Gastroenterolog\u00eda (MN 94517), creador del m\u00e9todo de Reseteo Intestinal (Programa B15), presenta su nuevo libro: \u201cAgotados\u201d, una obra que explora el impacto del cansancio cr\u00f3nico y sus m\u00faltiples causas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un mundo donde el agotamiento se ha convertido en una epidemia silenciosa, el Dr. Pereyra brinda un enfoque innovador basado en la medicina, la alimentaci\u00f3n y el bienestar emocional para recuperar la energ\u00eda de forma natural y sostenible.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-1.png\" alt=\"\" class=\"wp-image-24540\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-1.png 1024w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-1-300x169.png 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-1-768x432.png 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-1-747x420.png 747w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-1-696x392.png 696w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 ofrece \u201cAgotados\u201d?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2714 Diagn\u00f3stico personalizado: Incluye un \u201cauto test del cansancio\u201d para ayudar a los lectores a identificar el origen de su agotamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2714 Estrategias pr\u00e1cticas: Planes de alimentaci\u00f3n, recomendaciones de h\u00e1bitos saludables y el uso de suplementos y hongos medicinales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2714 Casos reales inspiradores: Relatos de personas que lograron superar el cansancio cr\u00f3nico.<br>\u2714 El enfoque m\u00e1s actualizado sobre el agotamiento: Basado en la experiencia cl\u00ednica y los \u00faltimos avances en medicina y nutrici\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-2.png\" alt=\"\" class=\"wp-image-24541\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-2.png 1024w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-2-300x169.png 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-2-768x432.png 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-2-747x420.png 747w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-2-696x392.png 696w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PASEO LA PLAZA<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Av. Corrientes 1660 \u2013 Capital Federal \u2013 Buenos Aires \u2013 Argentina<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono: 6320-5300<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entradas: Desde $ 34.000 \u2013 en boleter\u00eda del teatro o por Plateanet \u2013 Link:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.plateanet.com\/obra\/30831?obra=DR%20FACU%20PEREYRA%20EN%20AGOTADOS%20-%20RECUPERA%20TU%20ENERGIA%20Y%20BIENESTAR&amp;paso=inicio\">https:\/\/www.plateanet.com\/obra\/30831?obra=DR%20FACU%20PEREYRA%20EN%20AGOTADOS%20-%20RECUPERA%20TU%20ENERGIA%20Y%20BIENESTAR&amp;paso=inicio<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Funci\u00f3n: Lunes 11 de Agosto \u2013 20:00 horas&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias Marcela N\u00fa\u00f1ez por hacernos llegar la gacetilla de prensa del evento que realizar\u00e1 el Dr. Facundo Pereyra en el Paseo La Plaza.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"609\" height=\"609\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-4.jpg\" alt=\"\" class=\"wp-image-24542\" style=\"width:341px;height:auto\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-4.jpg 609w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-4-300x300.jpg 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-4-150x150.jpg 150w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra-4-420x420.jpg 420w\" sizes=\"auto, (max-width: 609px) 100vw, 609px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SOBRE EL DR. FACUNDO PEREYRA<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Dr. Facundo Pereyra es un referente en salud digestiva y bienestar. Desarrollador del Programa MDB15\u00ae (\u201cMedicina Digestiva y Bienestar en 15 d\u00edas\u201d) y creador del primer auto test de impacto extradigestivo de mal funcionamiento intestinal, su trabajo ha transformado la vida de miles de personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su primer libro, \u201cResetea tus intestinos\u201d, fue un best-seller internacional, liderando las listas de los m\u00e1s vendidos en 2022 y 2023. Tambi\u00e9n es autor de \u201cLa vida despu\u00e9s del reseteo\u201d y \u201cH\u00e1bitos: Gu\u00eda pr\u00e1ctica para armar rutinas saludables\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2024, fue distinguido con el Mart\u00edn Fierro Digital en la categor\u00eda \u201cMejor Contenido Tem\u00e1tico Profesional\u201d, reconociendo su impacto en la divulgaci\u00f3n cient\u00edfica y la educaci\u00f3n en salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de su labor como m\u00e9dico y escritor, el Dr. Pereyra es director m\u00e9dico de la Fundaci\u00f3n Manos que Ayudan y realiza aportes y colaboraciones en diferentes instituciones, municipios y comedores. Actualmente, atiende de manera virtual y presencial en Cipolletti, R\u00edo Negro, y comparte su conocimiento a trav\u00e9s de conferencias y sus redes sociales, donde re\u00fane a m\u00e1s de un mill\u00f3n y medio de seguidores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"&nbsp;\"><strong>Web:<\/strong>&nbsp;<\/a><a href=\"https:\/\/www.mdb15.com\/n.com.ar\">https:\/\/www.mdb15.com\/n.com.ar<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reconocido m\u00e9dico cl\u00ednico especialista en Medicina Interna y Gastroenterolog\u00eda (MN 94517), autor best-seller,&nbsp;Dr. Facundo Pereyra, luego de haber presentado su libro Agotados en varios teatros con \u00e9xito,&nbsp;vuelve por cuarta vez a la Sala Picasso del Paseo La Plaza. La cita ser\u00e1 el pr\u00f3ximo Lunes 11 de agosto a las 20:00 horas. Donde se abordar\u00e1 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":24544,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,39],"tags":[],"class_list":["post-24539","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-interes-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA - Sergio Lapegue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"El reconocido m\u00e9dico cl\u00ednico especialista en Medicina Interna y Gastroenterolog\u00eda (MN 94517), autor best-seller,&nbsp;Dr. Facundo Pereyra, luego de haber presentado su libro Agotados en varios teatros con \u00e9xito,&nbsp;vuelve por cuarta vez a la Sala Picasso del Paseo La Plaza. La cita ser\u00e1 el pr\u00f3ximo Lunes 11 de agosto a las 20:00 horas. Donde se abordar\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/danielernesto.montana\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-03T16:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"819\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel E. Monta\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/daner_004\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel E. Monta\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/\"},\"author\":{\"name\":\"Daniel E. Monta\u00f1a\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/9198e7dbab43c6d74d0fd5399af7c3cd\"},\"headline\":\"EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA\",\"datePublished\":\"2025-08-03T16:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/\"},\"wordCount\":606,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/El-Dr.-Facundo-Pereyra.jpg\",\"articleSection\":[\"Actualidad\",\"Inter\u00e9s General\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/\",\"name\":\"EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/El-Dr.-Facundo-Pereyra.jpg\",\"datePublished\":\"2025-08-03T16:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/El-Dr.-Facundo-Pereyra.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/El-Dr.-Facundo-Pereyra.jpg\",\"width\":819,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/08\\\/03\\\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/9198e7dbab43c6d74d0fd5399af7c3cd\",\"name\":\"Daniel E. Monta\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"caption\":\"Daniel E. Monta\u00f1a\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/danielernesto.montana\",\"https:\\\/\\\/instagram.com\\\/daniel_montana1961\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/daner_004\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/daniel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA - Sergio Lapegue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/","og_locale":"es_ES","og_type":"article","og_title":"EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA - Sergio Lapegue","og_description":"El reconocido m\u00e9dico cl\u00ednico especialista en Medicina Interna y Gastroenterolog\u00eda (MN 94517), autor best-seller,&nbsp;Dr. Facundo Pereyra, luego de haber presentado su libro Agotados en varios teatros con \u00e9xito,&nbsp;vuelve por cuarta vez a la Sala Picasso del Paseo La Plaza. La cita ser\u00e1 el pr\u00f3ximo Lunes 11 de agosto a las 20:00 horas. Donde se abordar\u00e1 [&hellip;]","og_url":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/danielernesto.montana","article_published_time":"2025-08-03T16:00:00+00:00","og_image":[{"width":819,"height":1024,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra.jpg","type":"image\/jpeg"}],"author":"Daniel E. Monta\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/daner_004","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Daniel E. Monta\u00f1a","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/"},"author":{"name":"Daniel E. Monta\u00f1a","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/9198e7dbab43c6d74d0fd5399af7c3cd"},"headline":"EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA","datePublished":"2025-08-03T16:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/"},"wordCount":606,"commentCount":0,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra.jpg","articleSection":["Actualidad","Inter\u00e9s General"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/","url":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/","name":"EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra.jpg","datePublished":"2025-08-03T16:00:00+00:00","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/08\/El-Dr.-Facundo-Pereyra.jpg","width":819,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2025\/08\/03\/el-dr-facundo-pereyra-continua-presentando-su-libro-agotados-en-el-paseo-la-plaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"EL DR. FACUNDO PEREYRA CONTINUA PRESENTANDO SU LIBRO \u201cAGOTADOS\u201d EN EL PASEO LA PLAZA"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"]},{"@type":"Person","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/9198e7dbab43c6d74d0fd5399af7c3cd","name":"Daniel E. Monta\u00f1a","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","caption":"Daniel E. Monta\u00f1a"},"sameAs":["https:\/\/facebook.com\/danielernesto.montana","https:\/\/instagram.com\/daniel_montana1961","https:\/\/x.com\/https:\/\/twitter.com\/daner_004"],"url":"https:\/\/sergiolapegue.com\/site\/author\/daniel\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/24539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=24539"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/24539\/revisions"}],"predecessor-version":[{"id":24545,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/24539\/revisions\/24545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/24544"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=24539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=24539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=24539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}