{"id":23646,"date":"2025-06-30T08:32:00","date_gmt":"2025-06-30T11:32:00","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=23646"},"modified":"2025-06-26T14:38:39","modified_gmt":"2025-06-26T17:38:39","slug":"gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/","title":{"rendered":"GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">De acuerdo a un relevamiento&nbsp;realizado en base a los avisos publicados por anunciantes en el portal de clasificados&nbsp;<strong>Zonaprop<\/strong>,<strong>&nbsp;el precio del alquiler en GBA norte sube un 3,9% en mayo&nbsp;<\/strong>y acumula un incremento del 17,8% en 2025, 3,1 puntos porcentuales por encima de la inflaci\u00f3n (14,7%). En los \u00faltimos doce meses, el precio del alquiler aument\u00f3 un 55%.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un departamento de dos ambientes en GBA norte tiene un precio de 616.329 pesos mensuales,&nbsp;<\/strong>mientras que uno de tres ambientes se alquila por 869.448 pesos mensuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Olivos se presenta como el barrio m\u00e1s caro para alquilar, con un precio medio de 743.502 pesos mensuales.<\/strong>&nbsp;Le siguen Villa Martelli (732.718 pesos mensuales) y Florida (716.310 pesos mensuales). En contrapartida,&nbsp;<strong>Villa Lynch&nbsp; registra la oferta m\u00e1s econ\u00f3mica, con un precio medio de 438.935 pesos mensuales.&nbsp;<\/strong>Jos\u00e9 Le\u00f3n Su\u00e1rez (460.303 pesos mensuales) y Boulogne Sur Mer (486.561 pesos mensuales) completan el ranking de la oferta m\u00e1s econ\u00f3mica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En el caso de GBA oeste-sur, el precio medio de un alquiler sube un 3,1% en mayo&nbsp;<\/strong>y en 2025 acumula un incremento del 20,1%, por encima de la inflaci\u00f3n (14,7%). En t\u00e9rminos reales, el incremento en este per\u00edodo fue del 5,4%. En los \u00faltimos doce meses, los valores subieron un 70,4%.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un departamento de dos ambientes y 50 m<\/strong><strong><sup>2<\/sup><\/strong><strong>&nbsp;se alquila por 490.829 pesos mensuales,<\/strong>&nbsp;mientras que uno de tres ambientes y 70 m<sup>2<\/sup>&nbsp;tiene un valor de 650.668 pesos mensuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Canning se posiciona primero en el ranking de barrios con la oferta m\u00e1s cara<\/strong>, con un precio de 636.476 pesos mensuales. Santos Lugares (612.899 pesos mensuales) y S\u00e1enz Pe\u00f1a (604.749 pesos mensuales) completan el podio. Por el contrario,&nbsp;<strong>Gonz\u00e1lez Cat\u00e1n registra la oferta m\u00e1s econ\u00f3mica, con un precio medio de 327.527 pesos por mes.&nbsp;<\/strong>Le siguen Luis Guill\u00f3n (362.700 pesos por mes) y Rafael Calzada (379.054 pesos por mes).&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"790\" height=\"444\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler04.webp\" alt=\"\" class=\"wp-image-23648\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler04.webp 790w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler04-300x169.webp 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler04-768x432.webp 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler04-747x420.webp 747w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler04-696x391.webp 696w\" sizes=\"auto, (max-width: 790px) 100vw, 790px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El metro cuadrado en GBA norte sube m\u00e1s del 5% en los \u00faltimos doce meses<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El metro cuadrado en GBA norte sube un 0,5% en mayo y se ubica en 2.309 d\u00f3lares.&nbsp;<\/strong>En 2025, acumula un incremento del 3,5%, mientras que en los \u00faltimos doce meses, la suba fue del 5,3%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El metro cuadrado en GBA norte es un 4,4% m\u00e1s accesible en comparaci\u00f3n a CABA (2.416 d\u00f3lares) y un 29% m\u00e1s caro que GBA oeste sur.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un departamento de dos ambientes y 50 m<\/strong><strong><sup>2<\/sup><\/strong><strong>&nbsp;se ubica en 112.899 d\u00f3lares,&nbsp;<\/strong>mientras que uno de tres ambientes y 70 m<sup>2<\/sup>&nbsp;tiene un valor de venta de 173.496 d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Lucila encabeza la lista de barrios con precios m\u00e1s caros para la compra, con un precio medio de 3.548 d\u00f3lares\/m<\/strong><strong><sup>2<\/sup><\/strong><strong>.<\/strong>&nbsp;Vicente L\u00f3pez (3.536 d\u00f3lares\/m<sup>2<\/sup>) y Olivos (3.128 d\u00f3lares\/m<sup>2<\/sup>) completan el podio. En contrapartida,<strong>&nbsp;Barrio Infico (916 d\u00f3lares\/m<\/strong><strong><sup>2<\/sup><\/strong><strong>),&nbsp;<\/strong>Jos\u00e9 C. Paz Centro (982 d\u00f3lares\/m<sup>2<\/sup>) y Jos\u00e9 C. Paz Oeste (1.047 d\u00f3lares\/m<sup>2<\/sup>) registran la oferta m\u00e1s econ\u00f3mica de GBA norte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado,<strong>&nbsp;el valor del metro cuadrado en GBA oeste- sur sube un 0,3% en mayo y se ubica en 1.625 d\u00f3lares, un 33% por debajo del valor de CABA.&nbsp;<\/strong>En 2025, los precios de venta acumulan un incremento del 1,2%, mientras que en los \u00faltimos doce meses, suben un 1,9%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un departamento de dos ambientes tiene un valor de 81.631 d\u00f3lares,&nbsp;<\/strong>mientras que uno de tres ambientes se ubica en 117.298 d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Trist\u00e1n Su\u00e1rez contin\u00faa primero en el ranking de barrios con la oferta m\u00e1s cara de GBA oeste-sur, con un precio de 2.911 d\u00f3lares\/m<\/strong><strong><sup>2<\/sup><\/strong><strong>.&nbsp;<\/strong>Le siguen Don Bosco y Villa Udaondo, con precios medios de 2.573 d\u00f3lares\/m<sup>2<\/sup>&nbsp;y 2.565 d\u00f3lares\/m<sup>2<\/sup>, respectivamente. Por el contrario,&nbsp;<strong>San Jos\u00e9 (511 d\u00f3lares\/m<\/strong><strong><sup>2<\/sup><\/strong><strong>),&nbsp;<\/strong>Don Orione (650 d\u00f3lares\/m<sup>2<\/sup>) y Parque San Mart\u00edn (711 d\u00f3lares\/m<sup>2<\/sup>) son los m\u00e1s econ\u00f3micos para la adquisici\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"535\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler02-1024x535.jpg\" alt=\"\" class=\"wp-image-23647\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler02-1024x535.jpg 1024w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler02-300x157.jpg 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler02-768x401.jpg 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler02-804x420.jpg 804w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler02-696x363.jpg 696w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler02-1068x558.jpg 1068w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler02.jpg 1128w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00bfQu\u00e9 barrios presentan mayor rentabilidad?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En GBA norte, la relaci\u00f3n alquiler\/precio contin\u00faa en alza y se ubica en 5,44%% anual.&nbsp;<\/strong>Actualmente se necesitan 18,4 a\u00f1os de alquiler para repagar la inversi\u00f3n inicial, un 27% menos que hace un a\u00f1o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bel\u00e9n de Escobar es el barrio que presenta mayor rentabilidad, con un retorno bruto del 8,3%.&nbsp;<\/strong>San Miguel y Bella Vista completan el podio, con un retorno del 8,2% y 8%, respectivamente.<strong>&nbsp;<\/strong>Por el contrario,&nbsp;<strong>La Lucila y Vicente L\u00f3pez son los barrios con menor ventaja rentable, con un retorno del 4% cada uno.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En&nbsp;<strong>GBA oeste-sur la relaci\u00f3n alquiler\/precio sube y se ubica en un 6,34% anual.&nbsp;<\/strong>Se necesitan 15,8 a\u00f1os de alquiler para repagar la inversi\u00f3n de compra, un 32% menos que hace un a\u00f1o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Llavallol, se posiciona como el mejor barrio para los inversores que buscan renta, con un retorno bruto del 10,5%.<\/strong>&nbsp;Le siguen El Jag\u00fcel y Gregorio de Laferrere con un promedio de 9,3% y 8,7% de retorno bruto, respectivamente.&nbsp; En contrapartida,&nbsp;<strong>los de menor ventaja rentable son Lomas de Zamora (5,1%), Adrogu\u00e9 (5,2%) y Temperley (5,3%).&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo a un relevamiento&nbsp;realizado en base a los avisos publicados por anunciantes en el portal de clasificados&nbsp;Zonaprop,&nbsp;el precio del alquiler en GBA norte sube un 3,9% en mayo&nbsp;y acumula un incremento del 17,8% en 2025, 3,1 puntos porcentuales por encima de la inflaci\u00f3n (14,7%). En los \u00faltimos doce meses, el precio del alquiler aument\u00f3 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":23649,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[240,242,241,2164,4184,1236],"class_list":["post-23646","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","tag-alquiler","tag-casa","tag-departamento","tag-inquilino","tag-valores","tag-venta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses - Sergio Lapegue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"De acuerdo a un relevamiento&nbsp;realizado en base a los avisos publicados por anunciantes en el portal de clasificados&nbsp;Zonaprop,&nbsp;el precio del alquiler en GBA norte sube un 3,9% en mayo&nbsp;y acumula un incremento del 17,8% en 2025, 3,1 puntos porcentuales por encima de la inflaci\u00f3n (14,7%). En los \u00faltimos doce meses, el precio del alquiler aument\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-30T11:32:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"495\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonardo Monta\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soytoto81\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Monta\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/\"},\"author\":{\"name\":\"Leonardo Monta\u00f1a\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/00adf937d010c7f79a180dc4916a40e0\"},\"headline\":\"GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses\",\"datePublished\":\"2025-06-30T11:32:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/\"},\"wordCount\":852,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/alquiler03.jpg\",\"keywords\":[\"alquiler\",\"casa\",\"departamento\",\"inquilino\",\"valores\",\"venta\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/\",\"name\":\"GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/alquiler03.jpg\",\"datePublished\":\"2025-06-30T11:32:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/alquiler03.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/alquiler03.jpg\",\"width\":880,\"height\":495},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/06\\\/30\\\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/00adf937d010c7f79a180dc4916a40e0\",\"name\":\"Leonardo Monta\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Leonardo-150x150.jpg\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Leonardo-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Leonardo-150x150.jpg\",\"caption\":\"Leonardo Monta\u00f1a\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soytoto81\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/leonardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses - Sergio Lapegue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/","og_locale":"es_ES","og_type":"article","og_title":"GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses - Sergio Lapegue","og_description":"De acuerdo a un relevamiento&nbsp;realizado en base a los avisos publicados por anunciantes en el portal de clasificados&nbsp;Zonaprop,&nbsp;el precio del alquiler en GBA norte sube un 3,9% en mayo&nbsp;y acumula un incremento del 17,8% en 2025, 3,1 puntos porcentuales por encima de la inflaci\u00f3n (14,7%). En los \u00faltimos doce meses, el precio del alquiler aument\u00f3 [&hellip;]","og_url":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2025-06-30T11:32:00+00:00","og_image":[{"width":880,"height":495,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler03.jpg","type":"image\/jpeg"}],"author":"Leonardo Monta\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/soytoto81","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Leonardo Monta\u00f1a","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/"},"author":{"name":"Leonardo Monta\u00f1a","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/00adf937d010c7f79a180dc4916a40e0"},"headline":"GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses","datePublished":"2025-06-30T11:32:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/"},"wordCount":852,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler03.jpg","keywords":["alquiler","casa","departamento","inquilino","valores","venta"],"articleSection":["Actualidad"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/","url":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/","name":"GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler03.jpg","datePublished":"2025-06-30T11:32:00+00:00","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler03.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/06\/alquiler03.jpg","width":880,"height":495},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2025\/06\/30\/gba-los-valores-del-alquiler-suben-mas-del-50-en-doce-meses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"GBA: los valores del alquiler suben m\u00e1s del 50% en doce meses"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"]},{"@type":"Person","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/00adf937d010c7f79a180dc4916a40e0","name":"Leonardo Monta\u00f1a","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Leonardo-150x150.jpg","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Leonardo-150x150.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Leonardo-150x150.jpg","caption":"Leonardo Monta\u00f1a"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/soytoto81"],"url":"https:\/\/sergiolapegue.com\/site\/author\/leonardo\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/23646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=23646"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/23646\/revisions"}],"predecessor-version":[{"id":23650,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/23646\/revisions\/23650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/23649"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=23646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=23646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=23646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}