{"id":23045,"date":"2025-05-27T09:00:00","date_gmt":"2025-05-27T12:00:00","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=23045"},"modified":"2025-05-27T02:33:48","modified_gmt":"2025-05-27T05:33:48","slug":"historias-para-ser-amadas-2","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/","title":{"rendered":"HISTORIAS PARA SER AMADAS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cHistorias para ser&nbsp;amadas\u201d, es un espect\u00e1culo teatral que re\u00fane cuatro comedias breves de Florencia Aroldi cuyo tema central es el amor y las relaciones interpersonales.&nbsp;El a\u00f1o pasado tuvo lugar la primera temporada. Ahora, el ciclo vuelve con el mismo elenco, pero con cuatro historias nuevas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El espect\u00e1culo se presenta todos los s\u00e1bados de mayo y junio a las 20:30 horas en el Teatro El Popular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Instagram de la obra:<\/strong>&nbsp;@historiasparaseramadas<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"718\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Nudo-corazon-1024x718.jpg\" alt=\"\" class=\"wp-image-23046\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Nudo-corazon-1024x718.jpg 1024w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Nudo-corazon-300x210.jpg 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Nudo-corazon-768x539.jpg 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Nudo-corazon-1536x1077.jpg 1536w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Nudo-corazon-2048x1436.jpg 2048w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Nudo-corazon-599x420.jpg 599w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Nudo-corazon-696x488.jpg 696w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Nudo-corazon-1068x749.jpg 1068w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Nudo-corazon-1920x1346.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NUDO CORAZ\u00d3N<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un psiquiatra recibe una visita fuera de agenda y poco convencional, que en nombre del amor intentar\u00e1 impedir que cometa un error tr\u00e1gico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">India Zamero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guillermo Montes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Direcci\u00f3n: Leonel Meunier<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Compatibles-1024x681.jpg\" alt=\"\" class=\"wp-image-23047\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Compatibles-1024x681.jpg 1024w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Compatibles-300x199.jpg 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Compatibles-768x511.jpg 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Compatibles-1536x1021.jpg 1536w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Compatibles-2048x1362.jpg 2048w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Compatibles-632x420.jpg 632w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Compatibles-696x463.jpg 696w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Compatibles-1068x710.jpg 1068w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Compatibles-1920x1277.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>COMPATIBLES<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pedro y Estanislao se encuentran por primera vez en un bar de un pueblo de la provincia de Buenos Aires por un tema que los involucra a los dos desde el d\u00eda en que nacieron. Un error involuntario cambio sus destinos para siempre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Omar Zaid<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alejandro Szadusrki<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Direcci\u00f3n: Florencia Aroldi<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"903\" height=\"1024\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Sillon-de-dos-cuerpos-903x1024.jpg\" alt=\"\" class=\"wp-image-23048\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Sillon-de-dos-cuerpos-903x1024.jpg 903w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Sillon-de-dos-cuerpos-265x300.jpg 265w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Sillon-de-dos-cuerpos-768x871.jpg 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Sillon-de-dos-cuerpos-1355x1536.jpg 1355w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Sillon-de-dos-cuerpos-1806x2048.jpg 1806w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Sillon-de-dos-cuerpos-370x420.jpg 370w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Sillon-de-dos-cuerpos-696x789.jpg 696w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Sillon-de-dos-cuerpos-1068x1211.jpg 1068w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Sillon-de-dos-cuerpos-1920x2177.jpg 1920w\" sizes=\"auto, (max-width: 903px) 100vw, 903px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SILL\u00d3N DE DOS CUERPOS <\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una pareja en crisis recurre a un controvertido m\u00e9todo para recuperar el deseo perdido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guadalupe Farina<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gast\u00f3n Giunta<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nancy Rossi<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Direcci\u00f3n: Gustavo Armas<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"718\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Hexagrama-52-1024x718.jpg\" alt=\"\" class=\"wp-image-23049\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Hexagrama-52-1024x718.jpg 1024w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Hexagrama-52-300x210.jpg 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Hexagrama-52-768x538.jpg 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Hexagrama-52-1536x1076.jpg 1536w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Hexagrama-52-2048x1435.jpg 2048w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Hexagrama-52-599x420.jpg 599w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Hexagrama-52-696x488.jpg 696w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Hexagrama-52-1068x748.jpg 1068w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-Hexagrama-52-1920x1345.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>HEXAGRAMA 52<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Perla asiste a una sesi\u00f3n de I Ching en busca de una confirmaci\u00f3n sobre su vida matrimonial. El encargado de guiarla es Josu\u00e9, un hombre felizmente casado. Lo que comienza como una sesi\u00f3n ordinaria pronto se ve envuelto en enredos y confusiones que conducen a un desenlace inesperado. Las vidas de ambos est\u00e1n conectadas de un modo que ninguno podr\u00eda imaginar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Magal\u00ed Meli\u00e1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Martin Navarro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Direcci\u00f3n: D\u00e9bora Longobardi<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"459\" height=\"392\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-1.jpeg\" alt=\"\" class=\"wp-image-23050\" style=\"width:696px;height:auto\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-1.jpeg 459w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas-1-300x256.jpeg 300w\" sizes=\"auto, (max-width: 459px) 100vw, 459px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TEATRO EL POPULAR<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chile 2080 \u2013 Capital Federal \u2013 Buenos Aires \u2013 Argentina<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entradas: $ 12.000 \u2013 en boleter\u00eda del teatro o por Alternativa Teatral<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Funciones: S\u00e1bados 20:30 horas \u2013&nbsp; Del 17\/05\/2025 al 28\/06\/2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias Guadalupe Farina por hacernos llegar la gacetilla de prensa del estreno de este espect\u00e1culo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cHistorias para ser&nbsp;amadas\u201d, es un espect\u00e1culo teatral que re\u00fane cuatro comedias breves de Florencia Aroldi cuyo tema central es el amor y las relaciones interpersonales.&nbsp;El a\u00f1o pasado tuvo lugar la primera temporada. Ahora, el ciclo vuelve con el mismo elenco, pero con cuatro historias nuevas. El espect\u00e1culo se presenta todos los s\u00e1bados de mayo y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23051,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,35],"tags":[],"class_list":["post-23045","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arte","category-teatro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HISTORIAS PARA SER AMADAS - Sergio Lapegue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HISTORIAS PARA SER AMADAS - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"\u201cHistorias para ser&nbsp;amadas\u201d, es un espect\u00e1culo teatral que re\u00fane cuatro comedias breves de Florencia Aroldi cuyo tema central es el amor y las relaciones interpersonales.&nbsp;El a\u00f1o pasado tuvo lugar la primera temporada. Ahora, el ciclo vuelve con el mismo elenco, pero con cuatro historias nuevas. El espect\u00e1culo se presenta todos los s\u00e1bados de mayo y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/danielernesto.montana\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-27T12:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel E. Monta\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/daner_004\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel E. Monta\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/\"},\"author\":{\"name\":\"Daniel E. Monta\u00f1a\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/9198e7dbab43c6d74d0fd5399af7c3cd\"},\"headline\":\"HISTORIAS PARA SER AMADAS\",\"datePublished\":\"2025-05-27T12:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/\"},\"wordCount\":320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Historias-para-ser-amadas.jpg\",\"articleSection\":[\"Arte\",\"Teatro\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/\",\"name\":\"HISTORIAS PARA SER AMADAS - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Historias-para-ser-amadas.jpg\",\"datePublished\":\"2025-05-27T12:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Historias-para-ser-amadas.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Historias-para-ser-amadas.jpg\",\"width\":1024,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/27\\\/historias-para-ser-amadas-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HISTORIAS PARA SER AMADAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/9198e7dbab43c6d74d0fd5399af7c3cd\",\"name\":\"Daniel E. Monta\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"caption\":\"Daniel E. Monta\u00f1a\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/danielernesto.montana\",\"https:\\\/\\\/instagram.com\\\/daniel_montana1961\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/daner_004\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/daniel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HISTORIAS PARA SER AMADAS - Sergio Lapegue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/","og_locale":"es_ES","og_type":"article","og_title":"HISTORIAS PARA SER AMADAS - Sergio Lapegue","og_description":"\u201cHistorias para ser&nbsp;amadas\u201d, es un espect\u00e1culo teatral que re\u00fane cuatro comedias breves de Florencia Aroldi cuyo tema central es el amor y las relaciones interpersonales.&nbsp;El a\u00f1o pasado tuvo lugar la primera temporada. Ahora, el ciclo vuelve con el mismo elenco, pero con cuatro historias nuevas. El espect\u00e1culo se presenta todos los s\u00e1bados de mayo y [&hellip;]","og_url":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/danielernesto.montana","article_published_time":"2025-05-27T12:00:00+00:00","og_image":[{"width":1024,"height":1280,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas.jpg","type":"image\/jpeg"}],"author":"Daniel E. Monta\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/daner_004","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Daniel E. Monta\u00f1a","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/"},"author":{"name":"Daniel E. Monta\u00f1a","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/9198e7dbab43c6d74d0fd5399af7c3cd"},"headline":"HISTORIAS PARA SER AMADAS","datePublished":"2025-05-27T12:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/"},"wordCount":320,"commentCount":0,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas.jpg","articleSection":["Arte","Teatro"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/","url":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/","name":"HISTORIAS PARA SER AMADAS - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas.jpg","datePublished":"2025-05-27T12:00:00+00:00","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/Historias-para-ser-amadas.jpg","width":1024,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/27\/historias-para-ser-amadas-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"HISTORIAS PARA SER AMADAS"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"]},{"@type":"Person","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/9198e7dbab43c6d74d0fd5399af7c3cd","name":"Daniel E. Monta\u00f1a","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","caption":"Daniel E. Monta\u00f1a"},"sameAs":["https:\/\/facebook.com\/danielernesto.montana","https:\/\/instagram.com\/daniel_montana1961","https:\/\/x.com\/https:\/\/twitter.com\/daner_004"],"url":"https:\/\/sergiolapegue.com\/site\/author\/daniel\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/23045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=23045"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/23045\/revisions"}],"predecessor-version":[{"id":23052,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/23045\/revisions\/23052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/23051"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=23045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=23045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=23045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}