{"id":22721,"date":"2025-05-12T11:06:10","date_gmt":"2025-05-12T14:06:10","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=22721"},"modified":"2025-05-12T11:06:11","modified_gmt":"2025-05-12T14:06:11","slug":"la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/","title":{"rendered":"La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a1Hola de nuevo, queridos amigos de&nbsp;<strong>La Uni\u00f3n<\/strong>! Hoy les quiero compartir unas palabras sobre la<strong>&nbsp;<a href=\"https:\/\/launion.com.ar\/nota\/47648\/2025\/05\/se-viene-la-expo-empleo-2025-en-la-facultad-de-ingenieria-de-lomas\" target=\"_blank\" rel=\"noreferrer noopener\">Universidad de Lomas de Zamora (UNLZ).&nbsp;<\/a><\/strong>M\u00e1s bien, la historia de sus inicios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A fines de la d\u00e9cada del 60, comenz\u00f3 a gestarse con fuerza en nuestro distrito el proyecto&nbsp;de contar con una universidad propia. Fue gracias al impulso sostenido de las organizaciones intermedias que ese anhelo se concret\u00f3 el 13 de octubre de 1972, cuando se promulg\u00f3 la Ley 19.888, mediante la cual se cre\u00f3 la&nbsp;<strong><a href=\"https:\/\/launion.com.ar\/nota\/47587\/2025\/05\/la-unlz-lanza-la-campana-de-reciclaje-de-articulos-electricos-y-electronicos\" target=\"_blank\" rel=\"noreferrer noopener\">Universidad Nacional de Lomas de Zamora<\/a><\/strong><a href=\"https:\/\/launion.com.ar\/nota\/47587\/2025\/05\/la-unlz-lanza-la-campana-de-reciclaje-de-articulos-electricos-y-electronicos\" target=\"_blank\" rel=\"noreferrer noopener\">, junto con otras casas de estudios.&nbsp;<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las gestiones finales, que permitieron hacer realidad esa aspiraci\u00f3n, se llevaron a cabo en 1971. Ese a\u00f1o se constituy\u00f3 una comisi\u00f3n prouniversidad encabezada por el intendente Enrique Roig, junto a los ingenieros N\u00e9stor Vinelli y Luis Mazoti, quien dirig\u00eda&nbsp;el Instituto Filot\u00e9cnico. La comisi\u00f3n, formada el 21 de diciembre, propuso que el amplio predio de Santa Catalina era el lugar m\u00e1s adecuado para instalar el futuro complejo universitario.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/launion.com.ar\/nota\/47516\/2025\/05\/historico--la-universidad-de-lomas-obtuvo-la-posesion-legal-de-sus-terrenos\" target=\"_blank\" rel=\"noreferrer noopener\">La fundaci\u00f3n de la&nbsp;<\/a><strong><a href=\"https:\/\/launion.com.ar\/nota\/47516\/2025\/05\/historico--la-universidad-de-lomas-obtuvo-la-posesion-legal-de-sus-terrenos\" target=\"_blank\" rel=\"noreferrer noopener\">UNLZ<\/a><\/strong>&nbsp;respondi\u00f3 tanto a la necesidad de reorganizar el sistema universitario nacional -especialmente en lo que respecta a las saturadas universidades de Buenos Aires y La Plata- como al fuerte aumento demogr\u00e1fico registrado entre 1960 y 1970,&nbsp;con un crecimiento del 51 % en Lomas y del 31 % en todo el Gran Buenos Aires.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso de aprobaci\u00f3n del proyecto avanz\u00f3 con tal rapidez que no se lleg\u00f3 a establecer un esquema presupuestario que contemplara fondos espec\u00edficos para obras de infraestructura. As\u00ed fue como se abrieron las inscripciones para tres carreras que buscaban&nbsp;marcar una l\u00ednea alternativa a las propuestas tradicionales: Licenciatura en Administraci\u00f3n, Ingenier\u00eda Rural y Licenciatura en Comunicaci\u00f3n Social.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las primeras actividades acad\u00e9micas arrancaron en abril de 1973 con el inicio del Ciclo Formativo Universitario. Las clases se dictaban por la noche en la&nbsp;<strong>Escuela Normal de Lomas (ENAM)<\/strong>, mientras que el Rectorado funcionaba en la<strong>&nbsp;Biblioteca Mentruyt.&nbsp;<\/strong>Tras una d\u00e9cada turbulenta, con varios hechos de violencia que marcaron la vida universitaria, la UNLZ retom\u00f3 su camino institucional en 1983.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, el campus de la UNLZ se extiende en el predio de Santa Catalina y en el complejo del Cruce de Lomas, al que se accede desde la avenida Juan XXIII, muy cerca de la Ruta Provincial 4. All\u00ed se encuentran las facultades de Ingenier\u00eda, Derecho, Ciencias&nbsp;Econ\u00f3micas y Ciencias Sociales, adem\u00e1s del Laboratorio de Medios y la Biblioteca Central.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, con casi decenas de miles de egresados y una reconocida trayectoria en diversas disciplinas, la<strong>&nbsp;UNLZ<\/strong>&nbsp;se ha convertido en una referencia clave dentro del \u00e1mbito acad\u00e9mico, con impacto en una regi\u00f3n habitada por m\u00e1s de 2.800.000 personas y con proyecci\u00f3n&nbsp;en distritos vecinos. Su prestigio tambi\u00e9n ha trascendido fronteras, ganando reconocimiento en numerosos pa\u00edses de Am\u00e9rica Latina. La UNLZ es un orgullo de nuestro partido. \u00a1Hasta la semana que viene, amigos!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em><a href=\"https:\/\/launion.com.ar\/nota\/47762\/2025\/05\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\" target=\"_blank\" rel=\"noreferrer noopener\">Art\u00edculo publicado en el diario La Uni\u00f3n.-<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Hola de nuevo, queridos amigos de&nbsp;La Uni\u00f3n! Hoy les quiero compartir unas palabras sobre la&nbsp;Universidad de Lomas de Zamora (UNLZ).&nbsp;M\u00e1s bien, la historia de sus inicios. A fines de la d\u00e9cada del 60, comenz\u00f3 a gestarse con fuerza en nuestro distrito el proyecto&nbsp;de contar con una universidad propia. Fue gracias al impulso sostenido de las [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":22722,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1276],"tags":[3774,1323,1277,4286,4285],"class_list":["post-22721","post","type-post","status-publish","format-standard","has-post-thumbnail","category-de-puno-y-letra-lomas-de-zamora","tag-educacion-2","tag-la-union","tag-lomas-de-zamora","tag-universidad-nacional-de-lomas-de-zamora","tag-unlz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60 - Sergio Lapegue<\/title>\n<meta name=\"description\" content=\"Las primeras carreras que se abrieron fueron: Licenciatura en Administraci\u00f3n, Ingenier\u00eda Rural y Licenciatura en Comunicaci\u00f3n Social.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60 - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"Las primeras carreras que se abrieron fueron: Licenciatura en Administraci\u00f3n, Ingenier\u00eda Rural y Licenciatura en Comunicaci\u00f3n Social.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-12T14:06:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-12T14:06:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/1123666.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Sergio Lapegue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sergiolapegue\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Lapegue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/\"},\"author\":{\"name\":\"Sergio Lapegue\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"headline\":\"La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60\",\"datePublished\":\"2025-05-12T14:06:10+00:00\",\"dateModified\":\"2025-05-12T14:06:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/\"},\"wordCount\":537,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1123666.webp\",\"keywords\":[\"educaci\u00f3n\",\"La Uni\u00f3n\",\"Lomas de Zamora\",\"Universidad Nacional de Lomas de Zamora\",\"UNLZ\"],\"articleSection\":[\"De Pu\u00f1o y Letra Lomas de Zamora\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/\",\"name\":\"La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60 - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1123666.webp\",\"datePublished\":\"2025-05-12T14:06:10+00:00\",\"dateModified\":\"2025-05-12T14:06:11+00:00\",\"description\":\"Las primeras carreras que se abrieron fueron: Licenciatura en Administraci\u00f3n, Ingenier\u00eda Rural y Licenciatura en Comunicaci\u00f3n Social.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1123666.webp\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1123666.webp\",\"width\":1000,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/05\\\/12\\\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/sergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60 - Sergio Lapegue","description":"Las primeras carreras que se abrieron fueron: Licenciatura en Administraci\u00f3n, Ingenier\u00eda Rural y Licenciatura en Comunicaci\u00f3n Social.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/","og_locale":"es_ES","og_type":"article","og_title":"La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60 - Sergio Lapegue","og_description":"Las primeras carreras que se abrieron fueron: Licenciatura en Administraci\u00f3n, Ingenier\u00eda Rural y Licenciatura en Comunicaci\u00f3n Social.","og_url":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2025-05-12T14:06:10+00:00","article_modified_time":"2025-05-12T14:06:11+00:00","og_image":[{"width":1000,"height":525,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/1123666.webp","type":"image\/webp"}],"author":"Sergio Lapegue","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sergiolapegue","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Sergio Lapegue","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/"},"author":{"name":"Sergio Lapegue","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"headline":"La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60","datePublished":"2025-05-12T14:06:10+00:00","dateModified":"2025-05-12T14:06:11+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/"},"wordCount":537,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/1123666.webp","keywords":["educaci\u00f3n","La Uni\u00f3n","Lomas de Zamora","Universidad Nacional de Lomas de Zamora","UNLZ"],"articleSection":["De Pu\u00f1o y Letra Lomas de Zamora"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/","url":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/","name":"La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60 - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/1123666.webp","datePublished":"2025-05-12T14:06:10+00:00","dateModified":"2025-05-12T14:06:11+00:00","description":"Las primeras carreras que se abrieron fueron: Licenciatura en Administraci\u00f3n, Ingenier\u00eda Rural y Licenciatura en Comunicaci\u00f3n Social.","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/1123666.webp","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/05\/1123666.webp","width":1000,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2025\/05\/12\/la-unlz-un-sueno-que-comenzo-a-gestarse-en-la-decada-del-60\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"La UNLZ, un sue\u00f1o que comenz\u00f3 a gestarse en la d\u00e9cada del 60"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"],"url":"https:\/\/sergiolapegue.com\/site\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/22721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=22721"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/22721\/revisions"}],"predecessor-version":[{"id":22723,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/22721\/revisions\/22723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/22722"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=22721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=22721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=22721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}