{"id":22142,"date":"2025-04-15T12:31:18","date_gmt":"2025-04-15T15:31:18","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=22142"},"modified":"2025-04-15T12:31:19","modified_gmt":"2025-04-15T15:31:19","slug":"la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/","title":{"rendered":"La historia detr\u00e1s de la llegada de los marineros nazis a Temperley"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La<strong>&nbsp;Segunda Guerra&nbsp;<\/strong>fue verdaderamente mundial, abarcando rincones en casi todos los continentes, incluido el nuestro. No solo eso: lleg\u00f3 casi hasta el patio de nuestras casas, literalmente. \u00bfNo me creen? Hoy los invito a conocer una historia incre\u00edble sobre la batalla del R\u00edo de la Plata, el \u00fanico episodio librado en Sudam\u00e9rica durante aquel terrible conflicto.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquella batalla naval se libr\u00f3 frente a las costas uruguayas el 13 de diciembre de 1939 y tuvo como principal protagonista al&nbsp;<a href=\"https:\/\/launion.com.ar\/nota\/33962\/2023\/12\/la-increible-historia-de-un-acorazado-nazi-en-temperley\" target=\"_blank\" rel=\"noreferrer noopener\">acorazado alem\u00e1n Admiral Graf Spee<\/a>, que desde hac\u00eda meses recorr\u00eda las aguas del Atl\u00e1ntico con la misi\u00f3n de destruir el tr\u00e1fico mercante del enemigo. En otras palabras, los jerarcas nazis habilitaban a los marinos del barco a comportarse como corsarios, atacar y saquear los barcos que le daban apoyo log\u00edstico y comercial a los pa\u00edses aliados.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras advertir que muchas de sus naves comerciantes hab\u00edan sido exitosamente atacadas por el&nbsp;<strong>Graf Spee<\/strong>, los ingleses se cansaron: aquel 13 de diciembre, tres cruceros brit\u00e1nicos que ven\u00edan persiguiendo&nbsp;<a href=\"https:\/\/launion.com.ar\/nota\/12434\/2021\/09\/segunda-guerra-mundial-un-acorazado-nazi-y-un-escondite-en-temperley\" target=\"_blank\" rel=\"noreferrer noopener\">al acorazado nazi&nbsp;<\/a>lo alcanzaron frente a la costa de&nbsp;<strong>Montevideo&nbsp;<\/strong>y, pese a la dura resistencia de los alemanes, los terminaron venciendo. Al ver que su buque estaba a punto de ser hundido, el capit\u00e1n Hans Langdorff decidi\u00f3 amarrar en el puerto de&nbsp;<strong>Montevideo<\/strong>. Sin posibilidades de volver a combatir, dej\u00f3 ir a pique a la nave en las aguas del R\u00edo de la Plata cuatro d\u00edas despu\u00e9s y se traslad\u00f3 hacia Buenos Aires junto al resto de los sobrevivientes.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El capit\u00e1n, derrotado y deprimido, se suicid\u00f3 en nuestra capital el 20 de diciembre. El resto de su tripulaci\u00f3n se quedar\u00eda vagando por la&nbsp;<strong>Argentina<\/strong>. As\u00ed es como llegamos a&nbsp;<strong>Lomas de Zamora.<\/strong>&nbsp;M\u00e1s precisamente, a&nbsp;<strong>Temperley<\/strong>. Como las autoridades nacionales hab\u00edan decidido dejarlos en libertad, algunos hombres decidieron afincarse en nuestro partido.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A metros de la casona de la quinta de Gatti (hoy un geri\u00e1trico ubicado en la esquina de las calles Esmeralda y Carlos Tejedor, en&nbsp;<strong>Villa Galicia<\/strong>) una familia alemana hab\u00eda comprado una quinta para alquilar caballos. Entre sus tantos clientes estaba el vecino&nbsp;<strong>Juan Buchanan<\/strong>, quien construy\u00f3 una pileta. All\u00ed sol\u00edan ir los marineros del Graf Spee para refrescarse durante el verano. Algunos volvieron a&nbsp;<strong>Alemania<\/strong>&nbsp;tras el fin de la guerra, pero muchos decidieron quedarse a vivir en nuestro partido. Y sus descendientes son nuestros vecinos. \u00a1Qu\u00e9 historia!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/launion.com.ar\/nota\/16671\/2025\/03\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>Art\u00edculo publicado en el diario La Uni\u00f3n.<\/em><\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La&nbsp;Segunda Guerra&nbsp;fue verdaderamente mundial, abarcando rincones en casi todos los continentes, incluido el nuestro. No solo eso: lleg\u00f3 casi hasta el patio de nuestras casas, literalmente. \u00bfNo me creen? Hoy los invito a conocer una historia incre\u00edble sobre la batalla del R\u00edo de la Plata, el \u00fanico episodio librado en Sudam\u00e9rica durante aquel terrible conflicto.&nbsp; [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":22145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1276],"tags":[3076,1323,3077,3075,1322],"class_list":["post-22142","post","type-post","status-publish","format-standard","has-post-thumbnail","category-de-puno-y-letra-lomas-de-zamora","tag-graf-spee","tag-la-union","tag-nazis","tag-segunda-guerra-mundial","tag-temperley"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La historia detr\u00e1s de la llegada de los marineros nazis a Temperley - Sergio Lapegue<\/title>\n<meta name=\"description\" content=\"Sol\u00edan ir en verano a una pileta a metros de la casona de la quinta de Gatti, hoy un geri\u00e1trico ubicado en Esmeralda y Carlos Tejedor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La historia detr\u00e1s de la llegada de los marineros nazis a Temperley - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"Sol\u00edan ir en verano a una pileta a metros de la casona de la quinta de Gatti, hoy un geri\u00e1trico ubicado en Esmeralda y Carlos Tejedor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-15T15:31:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-15T15:31:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/04\/1120750.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Sergio Lapegue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sergiolapegue\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Lapegue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/\"},\"author\":{\"name\":\"Sergio Lapegue\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"headline\":\"La historia detr\u00e1s de la llegada de los marineros nazis a Temperley\",\"datePublished\":\"2025-04-15T15:31:18+00:00\",\"dateModified\":\"2025-04-15T15:31:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/\"},\"wordCount\":458,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1120750.webp\",\"keywords\":[\"Graf Spee\",\"La Uni\u00f3n\",\"nazis\",\"Segunda Guerra Mundial\",\"Temperley\"],\"articleSection\":[\"De Pu\u00f1o y Letra Lomas de Zamora\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/\",\"name\":\"La historia detr\u00e1s de la llegada de los marineros nazis a Temperley - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1120750.webp\",\"datePublished\":\"2025-04-15T15:31:18+00:00\",\"dateModified\":\"2025-04-15T15:31:19+00:00\",\"description\":\"Sol\u00edan ir en verano a una pileta a metros de la casona de la quinta de Gatti, hoy un geri\u00e1trico ubicado en Esmeralda y Carlos Tejedor.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1120750.webp\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1120750.webp\",\"width\":1000,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2025\\\/04\\\/15\\\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La historia detr\u00e1s de la llegada de los marineros nazis a Temperley\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/sergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La historia detr\u00e1s de la llegada de los marineros nazis a Temperley - Sergio Lapegue","description":"Sol\u00edan ir en verano a una pileta a metros de la casona de la quinta de Gatti, hoy un geri\u00e1trico ubicado en Esmeralda y Carlos Tejedor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/","og_locale":"es_ES","og_type":"article","og_title":"La historia detr\u00e1s de la llegada de los marineros nazis a Temperley - Sergio Lapegue","og_description":"Sol\u00edan ir en verano a una pileta a metros de la casona de la quinta de Gatti, hoy un geri\u00e1trico ubicado en Esmeralda y Carlos Tejedor.","og_url":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2025-04-15T15:31:18+00:00","article_modified_time":"2025-04-15T15:31:19+00:00","og_image":[{"width":1000,"height":525,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/04\/1120750.webp","type":"image\/webp"}],"author":"Sergio Lapegue","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sergiolapegue","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Sergio Lapegue","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/"},"author":{"name":"Sergio Lapegue","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"headline":"La historia detr\u00e1s de la llegada de los marineros nazis a Temperley","datePublished":"2025-04-15T15:31:18+00:00","dateModified":"2025-04-15T15:31:19+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/"},"wordCount":458,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/04\/1120750.webp","keywords":["Graf Spee","La Uni\u00f3n","nazis","Segunda Guerra Mundial","Temperley"],"articleSection":["De Pu\u00f1o y Letra Lomas de Zamora"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/","url":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/","name":"La historia detr\u00e1s de la llegada de los marineros nazis a Temperley - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/04\/1120750.webp","datePublished":"2025-04-15T15:31:18+00:00","dateModified":"2025-04-15T15:31:19+00:00","description":"Sol\u00edan ir en verano a una pileta a metros de la casona de la quinta de Gatti, hoy un geri\u00e1trico ubicado en Esmeralda y Carlos Tejedor.","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/04\/1120750.webp","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/04\/1120750.webp","width":1000,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2025\/04\/15\/la-historia-detras-de-la-llegada-de-los-marineros-nazis-a-temperley\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"La historia detr\u00e1s de la llegada de los marineros nazis a Temperley"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"],"url":"https:\/\/sergiolapegue.com\/site\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/22142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=22142"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/22142\/revisions"}],"predecessor-version":[{"id":22146,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/22142\/revisions\/22146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/22145"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=22142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=22142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=22142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}