{"id":19722,"date":"2024-12-09T10:04:54","date_gmt":"2024-12-09T13:04:54","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=19722"},"modified":"2024-12-09T10:04:54","modified_gmt":"2024-12-09T13:04:54","slug":"la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/","title":{"rendered":"La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a1Hola, amigos! Nos volvemos a encontrar en las p\u00e1ginas de&nbsp;<strong>La Uni\u00f3n<\/strong>&nbsp;para compartir otra historia sobre nuestra querida ciudad. Hoy los invito a&nbsp;<strong>Villa La Perla<\/strong>, un barrio que ocupa 21 manzanas en&nbsp;<strong>Temperley<\/strong>&nbsp;y donde se encuentra la comunidad cat\u00f3lica de&nbsp;<strong>San Bonifacio.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el pasado, unas 200 familias de inmigrantes le dieron la impronta de una peque\u00f1a Alemania. La mayor\u00eda eran &#8220;suabos&#8221; provenientes de la regi\u00f3n del Danubio, de pa\u00edses como Hungr\u00eda, Rumania y la ex Yugoslavia. Sus antepasados, debido a problemas demogr\u00e1ficos,&nbsp;hab\u00edan emigrado masivamente de esas zonas des\u00e9rticas del Danubio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Formaron comunidades en las que el \u00fanico idioma era el alem\u00e1n, lo que les dio una gran cohesi\u00f3n en el tiempo y por el lugar donde se radicaron, son llamados &#8220;banater schwaben&#8221;. Con los a\u00f1os algunos regresaron a Alemania, otros se dirigieron a otras partes del&nbsp;mundo y el resto decidi\u00f3 permanecer en su territorio. En Lomas se nuclearon alrededor del templo la Sagrada Familia, el club y el colegio alem\u00e1n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera inmigraci\u00f3n fue despu\u00e9s de la Primera Guerra Mundial, la segunda alrededor de 1935 y el \u00faltimo grupo lo hizo entre los a\u00f1os 1949 y 1950. Inicialmente viv\u00edan en Pi\u00f1eiro, Avellaneda, pero el colegio que all\u00ed ten\u00edan fue confiscado en 1945 al entrar&nbsp;nuestro pa\u00eds en guerra con el Eje. M\u00e1s de la mitad de esa inmigraci\u00f3n se radic\u00f3 en Temperley en 1950 y el resto en la Ciudad de Buenos Aires, Avellaneda, Burzaco y Glew.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iglesia de la<strong>&nbsp;Sagrada Familia<\/strong>&nbsp;fue levantada en Albarrac\u00edn 49 y fue posible gracias a las gestiones hechas por monse\u00f1or&nbsp;<strong>Alejandro Schell&nbsp;<\/strong>cuando era p\u00e1rroco de&nbsp;<strong>Lomas de Zamora<\/strong>, ante un ente episcopal creado por los alemanes del exterior que funcionaba en Bonn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Los alemanes tambi\u00e9n fundaron, en 1946, la<strong>&nbsp;Sociedad Deportiva y Cultural Juventud del Sur<\/strong>, en Triunvirato 810, donde se jugaba a los bolos y al tenis criollo.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hundimiento del acorazado alem\u00e1n Graf von Spee, en la batalla del R\u00edo de la Plata, motiv\u00f3 el asilo de muchos marineros en el pa\u00eds. Esto tuvo repercusi\u00f3n en Temperley porque luego de que gran parte de la tripulaci\u00f3n estuvo internada en Sierra de la Ventana,&nbsp;al ser dejada en libertad, algunos hombres se afincaron en Lomas. Frente a la quinta de Gatti, en la calle Esmeralda, viv\u00eda la familia Olmos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cerca de ah\u00ed, en la quinta de Molin\u00e9, fue comprada por una familia alemana que alquilaba caballos. Entre sus clientes&nbsp;estaba el vecino Juan Buchanan, quien construy\u00f3 una pileta y a la cual sol\u00edan ir los marineros del Graf von Spee.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fin, amigos de La Uni\u00f3n, peque\u00f1as an\u00e9cdotas de nuestro pasado en Lomas, donde los inmigrantes europeos fueron grandes protagonistas. \u00a1Hasta la semana que viene!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em><a href=\"https:\/\/launion.com.ar\/nota\/43648\/2024\/12\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\" target=\"_blank\" rel=\"noreferrer noopener\">Art\u00edculo publicado en La Uni\u00f3n.-<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Hola, amigos! Nos volvemos a encontrar en las p\u00e1ginas de&nbsp;La Uni\u00f3n&nbsp;para compartir otra historia sobre nuestra querida ciudad. Hoy los invito a&nbsp;Villa La Perla, un barrio que ocupa 21 manzanas en&nbsp;Temperley&nbsp;y donde se encuentra la comunidad cat\u00f3lica de&nbsp;San Bonifacio. En el pasado, unas 200 familias de inmigrantes le dieron la impronta de una peque\u00f1a Alemania. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":19723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1276],"tags":[2636,2690,1323,1277,1322],"class_list":["post-19722","post","type-post","status-publish","format-standard","has-post-thumbnail","category-de-puno-y-letra-lomas-de-zamora","tag-alemania","tag-inmigracion","tag-la-union","tag-lomas-de-zamora","tag-temperley"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre - Sergio Lapegue<\/title>\n<meta name=\"description\" content=\"Se nuclearon alrededor del templo la Sagrada Familia, el club y el colegio alem\u00e1n. Muchos llegaron luego del hundimiento del Graf von Spee.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"Se nuclearon alrededor del templo la Sagrada Familia, el club y el colegio alem\u00e1n. Muchos llegaron luego del hundimiento del Graf von Spee.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T13:04:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/12\/1114217.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Sergio Lapegue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/sergiolapegue\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Lapegue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/\"},\"author\":{\"name\":\"Sergio Lapegue\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"headline\":\"La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre\",\"datePublished\":\"2024-12-09T13:04:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/\"},\"wordCount\":524,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1114217.webp\",\"keywords\":[\"alemania\",\"inmigraci\u00f3n\",\"La Uni\u00f3n\",\"Lomas de Zamora\",\"Temperley\"],\"articleSection\":[\"De Pu\u00f1o y Letra Lomas de Zamora\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/\",\"name\":\"La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1114217.webp\",\"datePublished\":\"2024-12-09T13:04:54+00:00\",\"description\":\"Se nuclearon alrededor del templo la Sagrada Familia, el club y el colegio alem\u00e1n. Muchos llegaron luego del hundimiento del Graf von Spee.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1114217.webp\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1114217.webp\",\"width\":1000,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/12\\\/09\\\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/sergio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre - Sergio Lapegue","description":"Se nuclearon alrededor del templo la Sagrada Familia, el club y el colegio alem\u00e1n. Muchos llegaron luego del hundimiento del Graf von Spee.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/","og_locale":"es_ES","og_type":"article","og_title":"La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre - Sergio Lapegue","og_description":"Se nuclearon alrededor del templo la Sagrada Familia, el club y el colegio alem\u00e1n. Muchos llegaron luego del hundimiento del Graf von Spee.","og_url":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2024-12-09T13:04:54+00:00","og_image":[{"width":1000,"height":525,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/12\/1114217.webp","type":"image\/webp"}],"author":"Sergio Lapegue","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/sergiolapegue","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Sergio Lapegue","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/"},"author":{"name":"Sergio Lapegue","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"headline":"La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre","datePublished":"2024-12-09T13:04:54+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/"},"wordCount":524,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/12\/1114217.webp","keywords":["alemania","inmigraci\u00f3n","La Uni\u00f3n","Lomas de Zamora","Temperley"],"articleSection":["De Pu\u00f1o y Letra Lomas de Zamora"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/","url":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/","name":"La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/12\/1114217.webp","datePublished":"2024-12-09T13:04:54+00:00","description":"Se nuclearon alrededor del templo la Sagrada Familia, el club y el colegio alem\u00e1n. Muchos llegaron luego del hundimiento del Graf von Spee.","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/12\/1114217.webp","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/12\/1114217.webp","width":1000,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2024\/12\/09\/la-comunidad-alemana-llego-a-temperley-y-la-cambio-para-siempre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"La comunidad alemana lleg\u00f3 a Temperley y la cambi\u00f3 para siempre"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"],"url":"https:\/\/sergiolapegue.com\/site\/author\/sergio\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/19722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=19722"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/19722\/revisions"}],"predecessor-version":[{"id":19724,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/19722\/revisions\/19724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/19723"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=19722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=19722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=19722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}