{"id":18517,"date":"2024-10-15T09:49:00","date_gmt":"2024-10-15T12:49:00","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=18517"},"modified":"2024-10-10T15:51:25","modified_gmt":"2024-10-10T18:51:25","slug":"como-reducir-las-discusiones-de-pareja","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/","title":{"rendered":"\u00bfC\u00f3mo reducir las discusiones de pareja?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En todas las relaciones de pareja se presentan conflictos, eso es inevitable porque todos tenemos diferencias algunas vez. Ahora bien, la cuesti\u00f3n es c\u00f3mo lo manejamos en el momento. Si un malentendido no se gestiona adecuadamente, puede escalar, y generar un conflicto a\u00fan mayor.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una estrategia simple que siempre les sugiero a mis pacientes, es tomar una pausa, que puede ser, salir un rato a caminar, darse un ba\u00f1o, o simplemente cambiar de ambiente, lo que mejor le funcione a cada uno, para poder pensar con tranquilidad, bajar la espuma, y reflexionar de qu\u00e9 manera vamos a abordar la situaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando no se gestionan las emociones como el enojo, y pasamos por alto esa pausa, corremos el riesgo de que se nuble nuestra visi\u00f3n y nuestra capacidad de comunicaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces en vez de expresar verdaderamente lo que sentimos ante una problem\u00e1tica, terminamos reaccionando por impulso y diciendo cosas que no queremos decir, que por supuesto hieren a nuestra pareja, y van generando a largo plazo heridas profundas en la relaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si optamos por tomar una pausa, vamos a poder pensar lo que queremos decir, y c\u00f3mo lo podemos decir de la manera m\u00e1s asertiva posible. De esta manera nos estamos dando la oportunidad de ser escuchados y validados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por supuesto que con tomar una pausa, no me refiero a permanecer d\u00edas sin hablar con nuestra pareja, porque eso solo nos lleva a evitar el conflicto y agravar cada vez m\u00e1s la situaci\u00f3n, porque de todas maneras el problema va a seguir estando ah\u00ed presente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"690\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0911-1024x690.jpg\" alt=\"\" class=\"wp-image-18519\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0911-1024x690.jpg 1024w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0911-300x202.jpg 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0911-768x517.jpg 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0911-624x420.jpg 624w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0911-696x469.jpg 696w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0911-1068x719.jpg 1068w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0911.jpg 1090w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los temas importantes en una relaci\u00f3n deben hablarse, pero en el momento adecuado, cuando ambos est\u00e9n tranquilos para conversar, y as\u00ed poder llegar a acuerdos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que aclarar, que los problemas por lo general no se resuelven con una sola conversaci\u00f3n, y seguramente sea necesario m\u00e1s adelante volver a retomarlo. Despu\u00e9s de un intercambio, es importante que cada uno pueda darse un tiempo para procesarlo y pensar c\u00f3mo mejorarlo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poder hablar con nuestra pareja libremente sobre c\u00f3mo nos sentimos, y ser validados, no solo permite solucionar conflictos, sino que aporta al crecimiento del v\u00ednculo.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En todas las relaciones de pareja se presentan conflictos, eso es inevitable porque todos tenemos diferencias algunas vez. Ahora bien, la cuesti\u00f3n es c\u00f3mo lo manejamos en el momento. Si un malentendido no se gestiona adecuadamente, puede escalar, y generar un conflicto a\u00fan mayor.&nbsp; Una estrategia simple que siempre les sugiero a mis pacientes, es [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":18518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3596],"tags":[3861,3860,1535,1595,3399],"class_list":["post-18517","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vinculos","tag-conflicto","tag-discusion","tag-novio","tag-pareja","tag-vinculo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo reducir las discusiones de pareja? - Sergio Lapegue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo reducir las discusiones de pareja? - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"En todas las relaciones de pareja se presentan conflictos, eso es inevitable porque todos tenemos diferencias algunas vez. Ahora bien, la cuesti\u00f3n es c\u00f3mo lo manejamos en el momento. Si un malentendido no se gestiona adecuadamente, puede escalar, y generar un conflicto a\u00fan mayor.&nbsp; Una estrategia simple que siempre les sugiero a mis pacientes, es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-15T12:49:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0910.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1117\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jazm\u00edn Presa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jazm\u00edn Presa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/\"},\"author\":{\"name\":\"Jazm\u00edn Presa\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/165bcfb343338114c3f159e1a0c1daaf\"},\"headline\":\"\u00bfC\u00f3mo reducir las discusiones de pareja?\",\"datePublished\":\"2024-10-15T12:49:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/\"},\"wordCount\":384,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_0910.jpg\",\"keywords\":[\"conflicto\",\"discusion\",\"novio\",\"pareja\",\"vinculo\"],\"articleSection\":[\"V\u00ednculos\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/\",\"name\":\"\u00bfC\u00f3mo reducir las discusiones de pareja? - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_0910.jpg\",\"datePublished\":\"2024-10-15T12:49:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_0910.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_0910.jpg\",\"width\":1117,\"height\":687},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/10\\\/15\\\/como-reducir-las-discusiones-de-pareja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo reducir las discusiones de pareja?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/165bcfb343338114c3f159e1a0c1daaf\",\"name\":\"Jazm\u00edn Presa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/jazminPresa-150x150.jpg\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/jazminPresa-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/jazminPresa-150x150.jpg\",\"caption\":\"Jazm\u00edn Presa\"},\"description\":\"Psic\u00f3loga Cl\u00ednica Especialista en pareja. Autora: \u201c\u00c1mate y luego ama a quien t\u00fa quieras\u201d\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/terapiaonline_jp\\\/\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/jazminpresa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo reducir las discusiones de pareja? - Sergio Lapegue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo reducir las discusiones de pareja? - Sergio Lapegue","og_description":"En todas las relaciones de pareja se presentan conflictos, eso es inevitable porque todos tenemos diferencias algunas vez. Ahora bien, la cuesti\u00f3n es c\u00f3mo lo manejamos en el momento. Si un malentendido no se gestiona adecuadamente, puede escalar, y generar un conflicto a\u00fan mayor.&nbsp; Una estrategia simple que siempre les sugiero a mis pacientes, es [&hellip;]","og_url":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2024-10-15T12:49:00+00:00","og_image":[{"width":1117,"height":687,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0910.jpg","type":"image\/jpeg"}],"author":"Jazm\u00edn Presa","twitter_card":"summary_large_image","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Jazm\u00edn Presa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/"},"author":{"name":"Jazm\u00edn Presa","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/165bcfb343338114c3f159e1a0c1daaf"},"headline":"\u00bfC\u00f3mo reducir las discusiones de pareja?","datePublished":"2024-10-15T12:49:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/"},"wordCount":384,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0910.jpg","keywords":["conflicto","discusion","novio","pareja","vinculo"],"articleSection":["V\u00ednculos"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/","url":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/","name":"\u00bfC\u00f3mo reducir las discusiones de pareja? - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0910.jpg","datePublished":"2024-10-15T12:49:00+00:00","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0910.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/10\/IMG_0910.jpg","width":1117,"height":687},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2024\/10\/15\/como-reducir-las-discusiones-de-pareja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo reducir las discusiones de pareja?"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"]},{"@type":"Person","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/165bcfb343338114c3f159e1a0c1daaf","name":"Jazm\u00edn Presa","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/06\/jazminPresa-150x150.jpg","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/06\/jazminPresa-150x150.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/06\/jazminPresa-150x150.jpg","caption":"Jazm\u00edn Presa"},"description":"Psic\u00f3loga Cl\u00ednica Especialista en pareja. Autora: \u201c\u00c1mate y luego ama a quien t\u00fa quieras\u201d","sameAs":["https:\/\/www.instagram.com\/terapiaonline_jp\/"],"url":"https:\/\/sergiolapegue.com\/site\/author\/jazminpresa\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/18517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=18517"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/18517\/revisions"}],"predecessor-version":[{"id":18520,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/18517\/revisions\/18520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/18518"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=18517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=18517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=18517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}