{"id":17335,"date":"2024-08-26T12:55:34","date_gmt":"2024-08-26T15:55:34","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=17335"},"modified":"2024-08-26T12:55:35","modified_gmt":"2024-08-26T15:55:35","slug":"hit-astral-de-la-semana-venus-entra-en-libra","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/","title":{"rendered":"HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Llega el \u00faltimo lunes del mes de agosto y esta semana tenemos novedades respecto de MERCURIO que ya retomar\u00e1 su movimiento directo desde LEO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo lo que hayamos trabajado durante las anteriores empezar\u00e1 a darnos la claridad que necesitamos Y seguramente muchas fichas empiecen a caer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta semana adem\u00e1s VENUS cambia de signo e ingresa en LIBRA, su casa natural. Esta energ\u00eda, nos pide que nos abramos m\u00e1s a la vida social, que estemos receptivos a nivel coraz\u00f3n, que busquemos acuerdos y reconciliaciones.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La balanza libriana, seguramente nos pida poner orden las relaciones donde nos estemos sintiendo desatendidos,&nbsp; que hagamos valer nuestro punto de vista con altura y no sentir que solo luchando se consiguen las cosas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VENUS con LIBRA, buscar\u00e1 el di\u00e1logo, escuchar y sobre todas las cosas, traernos la oportunidad de aceptar las diferencias, porque son las que m\u00e1s nos enriquecen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SIGNOS DESTACADOS DE LA SEMANA: <\/strong>&nbsp;Una semana donde los signos de aire sobre todo, mover\u00e1n el avispero emocional d\u00e1ndose a lo social. La vida les pide abrir el coraz\u00f3n y predisponerse a aprender algo nuevo del amor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FRASE GU\u00cdA PARA ESTA SEMANA: <\/strong>\u201cDe a dos todo es mejor.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ARCANOS ALIADOS DEL TAROT:&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LOS AMANTES \/<\/strong> Esta carta te recuerda que el amor es un espejo que siempre te devuelve tu propia imagen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"736\" height=\"736\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/2-2.jpg\" alt=\"\" class=\"wp-image-17336\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/2-2.jpg 736w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/2-2-300x300.jpg 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/2-2-150x150.jpg 150w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/2-2-420x420.jpg 420w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/2-2-696x696.jpg 696w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PREDICCIONES:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SIGNOS DE FUEGO #ARIES #LEO #SAGITARIO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s vida social y la llegada de personas nuevas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Momento para abrir el coraz\u00f3n sin verg\u00fcenza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la pareja se arma un equipo poderoso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y si est\u00e1n buscando una, se pueden sorprender para bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SIGNOS DE TIERRA #TAURO #VIRGO #CAPRICORNIO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La econom\u00eda repunta y aparecen personas aliadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La creatividad es la fuente principal de los ingresos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dediquen tiempo de calidad a las cosas son valiosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trabajen en su estabilidad emocional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SIGNOS DE AIRE #G\u00c9MINIS #LIBRA #ACUARIO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Momento perfecto para ocuparse de la imagen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Darse un masaje, hacer un cambio de look.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La clave es valorarse, no se bajen el precio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s energ\u00eda al disfrute y menos a la exigencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SIGNOS DE AGUA #C\u00c1NCER #ESCORPIO #PISCIS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00edas para estar junto con la familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es el momento perfecto para poner linda la casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recarguen las pilas emocionales consumiendo arte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La paz interior se construye todos los d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llega el \u00faltimo lunes del mes de agosto y esta semana tenemos novedades respecto de MERCURIO que ya retomar\u00e1 su movimiento directo desde LEO. Todo lo que hayamos trabajado durante las anteriores empezar\u00e1 a darnos la claridad que necesitamos Y seguramente muchas fichas empiecen a caer. Esta semana adem\u00e1s VENUS cambia de signo e ingresa [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":17337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2901],"tags":[2916,3282,3515,3750,3522,2907,2906,2917],"class_list":["post-17335","post","type-post","status-publish","format-standard","has-post-thumbnail","category-astrotarot","tag-astral","tag-astros","tag-hit","tag-horoscopos","tag-leo","tag-libra","tag-mercurio","tag-venus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA - Sergio Lapegue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"Llega el \u00faltimo lunes del mes de agosto y esta semana tenemos novedades respecto de MERCURIO que ya retomar\u00e1 su movimiento directo desde LEO. Todo lo que hayamos trabajado durante las anteriores empezar\u00e1 a darnos la claridad que necesitamos Y seguramente muchas fichas empiecen a caer. Esta semana adem\u00e1s VENUS cambia de signo e ingresa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-26T15:55:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-26T15:55:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"555\" \/>\n\t<meta property=\"og:image:height\" content=\"707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Victoria Garc\u00eda Garcilazo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Victoria Garc\u00eda Garcilazo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/\"},\"author\":{\"name\":\"Victoria Garc\u00eda Garcilazo\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/038a19a76176d528a1a27ac17e18af68\"},\"headline\":\"HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA\",\"datePublished\":\"2024-08-26T15:55:34+00:00\",\"dateModified\":\"2024-08-26T15:55:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/\"},\"wordCount\":402,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/1-2.jpg\",\"keywords\":[\"astral\",\"astros\",\"hit\",\"horoscopos\",\"leo\",\"libra\",\"mercurio\",\"venus\"],\"articleSection\":[\"Astrotarot\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/\",\"name\":\"HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/1-2.jpg\",\"datePublished\":\"2024-08-26T15:55:34+00:00\",\"dateModified\":\"2024-08-26T15:55:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/1-2.jpg\",\"width\":555,\"height\":707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/08\\\/26\\\/hit-astral-de-la-semana-venus-entra-en-libra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/038a19a76176d528a1a27ac17e18af68\",\"name\":\"Victoria Garc\u00eda Garcilazo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/victoriaGarciaGarcilazo-150x150.jpg\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/victoriaGarciaGarcilazo-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/victoriaGarciaGarcilazo-150x150.jpg\",\"caption\":\"Victoria Garc\u00eda Garcilazo\"},\"sameAs\":[\"https:\\\/\\\/lavictoriadevenus.com\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lavictoriadevenus\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPAWzfQij6wJRHSTN5wi3Mg\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/victoria\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA - Sergio Lapegue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/","og_locale":"es_ES","og_type":"article","og_title":"HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA - Sergio Lapegue","og_description":"Llega el \u00faltimo lunes del mes de agosto y esta semana tenemos novedades respecto de MERCURIO que ya retomar\u00e1 su movimiento directo desde LEO. Todo lo que hayamos trabajado durante las anteriores empezar\u00e1 a darnos la claridad que necesitamos Y seguramente muchas fichas empiecen a caer. Esta semana adem\u00e1s VENUS cambia de signo e ingresa [&hellip;]","og_url":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2024-08-26T15:55:34+00:00","article_modified_time":"2024-08-26T15:55:35+00:00","og_image":[{"width":555,"height":707,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/1-2.jpg","type":"image\/jpeg"}],"author":"Victoria Garc\u00eda Garcilazo","twitter_card":"summary_large_image","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Victoria Garc\u00eda Garcilazo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/"},"author":{"name":"Victoria Garc\u00eda Garcilazo","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/038a19a76176d528a1a27ac17e18af68"},"headline":"HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA","datePublished":"2024-08-26T15:55:34+00:00","dateModified":"2024-08-26T15:55:35+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/"},"wordCount":402,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/1-2.jpg","keywords":["astral","astros","hit","horoscopos","leo","libra","mercurio","venus"],"articleSection":["Astrotarot"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/","url":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/","name":"HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/1-2.jpg","datePublished":"2024-08-26T15:55:34+00:00","dateModified":"2024-08-26T15:55:35+00:00","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/1-2.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/08\/1-2.jpg","width":555,"height":707},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2024\/08\/26\/hit-astral-de-la-semana-venus-entra-en-libra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"HIT ASTRAL DE LA SEMANA: VENUS entra en LIBRA"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"]},{"@type":"Person","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/038a19a76176d528a1a27ac17e18af68","name":"Victoria Garc\u00eda Garcilazo","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/12\/victoriaGarciaGarcilazo-150x150.jpg","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/12\/victoriaGarciaGarcilazo-150x150.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2025\/12\/victoriaGarciaGarcilazo-150x150.jpg","caption":"Victoria Garc\u00eda Garcilazo"},"sameAs":["https:\/\/lavictoriadevenus.com\/","https:\/\/www.instagram.com\/lavictoriadevenus\/","https:\/\/www.youtube.com\/channel\/UCPAWzfQij6wJRHSTN5wi3Mg"],"url":"https:\/\/sergiolapegue.com\/site\/author\/victoria\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/17335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=17335"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/17335\/revisions"}],"predecessor-version":[{"id":17338,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/17335\/revisions\/17338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/17337"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=17335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=17335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=17335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}