{"id":15183,"date":"2024-05-28T05:00:00","date_gmt":"2024-05-28T08:00:00","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=15183"},"modified":"2024-05-28T01:37:13","modified_gmt":"2024-05-28T04:37:13","slug":"astroclap","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/","title":{"rendered":"ASTROCLAP"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a1AstroClap! es un unipersonal de humor y astrolog\u00eda. En formato de experiencia teatral tipo stand up se explorar\u00e1n los 12 signos del zodiaco a trav\u00e9s del humor, descubriendo c\u00f3mo las energ\u00edas c\u00f3smicas influyen en nuestras vidas de una manera divertida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el aventurero Aries, hasta el sensible e intuitivo Piscis, cada signo tiene su propia magia que nos hace \u00fanicos. AstroClap! es una obra para conectarse con tus sentimientos y explorar junto a Clara S\u00e1enz sobre c\u00f3mo los astros moldean nuestras vidas de una manera tan aut\u00e9ntica y real.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Clara S\u00e1enz vincula todos sus conocimientos de astrolog\u00eda, oratoria y coach ontol\u00f3gico junto a sus pasiones por el clown y la actuaci\u00f3n para la creaci\u00f3n de este espect\u00e1culo teatral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de sus historias personales Clara recorre todos los signos, sus conexiones y aspectos con los que cada persona del p\u00fablico puede identificarse a trav\u00e9s de situaciones cotidianas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Disfruta de un hermoso viaje energ\u00e9tico!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-683x1024.jpg\" alt=\"\" class=\"wp-image-15184\" style=\"width:696px;height:auto\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-683x1024.jpg 683w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-200x300.jpg 200w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-768x1152.jpg 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-1024x1536.jpg 1024w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-1365x2048.jpg 1365w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-280x420.jpg 280w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-696x1044.jpg 696w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-1068x1602.jpg 1068w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-1920x2880.jpg 1920w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-3-scaled.jpg 1706w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FICHA T\u00c9CNICO ART\u00cdSTICA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dramaturgia:<\/strong> Clara S\u00e1enz<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Interprete:<\/strong> Clara S\u00e1enz<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Iluminaci\u00f3n:<\/strong> Sebasti\u00e1n Mart\u00ednez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Asistente de direcci\u00f3n:<\/strong> Micaela Valiente<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Producci\u00f3n audiovisual:<\/strong> Francisco Quesada<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Direcci\u00f3n:<\/strong> Gonzalo Hern\u00e1n Rodolico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Etiquetas:<\/strong> @astro.cla @micaelavaliante @gonzalorodolico @franquesada.av<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Clasificaci\u00f3n:<\/strong> Teatro \u2013 Presencial \u2013 Adultos<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-1-1024x683.jpg\" alt=\"\" class=\"wp-image-15185\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-1-1024x683.jpg 1024w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-1-300x200.jpg 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-1-768x512.jpg 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-1-1536x1024.jpg 1536w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-1-2048x1366.jpg 2048w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-1-630x420.jpg 630w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-1-696x464.jpg 696w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-1-1068x712.jpg 1068w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-1-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EL PISO &#8211; CULTURA ESC\u00c9NICA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hidalgo 878 \u2013 Capital Federal \u2013 Buenos Aires \u2013 Argentina<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono: 112 185-8359<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entradas: $ 7.000 \u2013 en boleter\u00eda del lugar o por Alternativa Teatral<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Funciones: Viernes 31\/05\/2024 \u2013 21:00 horas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0 S\u00e1bado 01\/06; 22\/06 y 29\/06 \u2013 23:00 horas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias Florencia Carrasco por hacernos llegar la gacetilla de prensa del unipersonal que realiza Clara S\u00e1enz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1AstroClap! es un unipersonal de humor y astrolog\u00eda. En formato de experiencia teatral tipo stand up se explorar\u00e1n los 12 signos del zodiaco a trav\u00e9s del humor, descubriendo c\u00f3mo las energ\u00edas c\u00f3smicas influyen en nuestras vidas de una manera divertida. Desde el aventurero Aries, hasta el sensible e intuitivo Piscis, cada signo tiene su propia [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":15186,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,35],"tags":[],"class_list":["post-15183","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arte","category-teatro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASTROCLAP - Sergio Lapegue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASTROCLAP - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"\u00a1AstroClap! es un unipersonal de humor y astrolog\u00eda. En formato de experiencia teatral tipo stand up se explorar\u00e1n los 12 signos del zodiaco a trav\u00e9s del humor, descubriendo c\u00f3mo las energ\u00edas c\u00f3smicas influyen en nuestras vidas de una manera divertida. Desde el aventurero Aries, hasta el sensible e intuitivo Piscis, cada signo tiene su propia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/danielernesto.montana\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-28T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel E. Monta\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/daner_004\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel E. Monta\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/\"},\"author\":{\"name\":\"Daniel E. Monta\u00f1a\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/9198e7dbab43c6d74d0fd5399af7c3cd\"},\"headline\":\"ASTROCLAP\",\"datePublished\":\"2024-05-28T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/\"},\"wordCount\":269,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Astroclap-2-scaled.jpg\",\"articleSection\":[\"Arte\",\"Teatro\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/\",\"name\":\"ASTROCLAP - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Astroclap-2-scaled.jpg\",\"datePublished\":\"2024-05-28T08:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Astroclap-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Astroclap-2-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/05\\\/28\\\/astroclap\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASTROCLAP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/9198e7dbab43c6d74d0fd5399af7c3cd\",\"name\":\"Daniel E. Monta\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Daniel-150x150.jpg\",\"caption\":\"Daniel E. Monta\u00f1a\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/danielernesto.montana\",\"https:\\\/\\\/instagram.com\\\/daniel_montana1961\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/daner_004\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/daniel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASTROCLAP - Sergio Lapegue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/","og_locale":"es_ES","og_type":"article","og_title":"ASTROCLAP - Sergio Lapegue","og_description":"\u00a1AstroClap! es un unipersonal de humor y astrolog\u00eda. En formato de experiencia teatral tipo stand up se explorar\u00e1n los 12 signos del zodiaco a trav\u00e9s del humor, descubriendo c\u00f3mo las energ\u00edas c\u00f3smicas influyen en nuestras vidas de una manera divertida. Desde el aventurero Aries, hasta el sensible e intuitivo Piscis, cada signo tiene su propia [&hellip;]","og_url":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_author":"https:\/\/facebook.com\/danielernesto.montana","article_published_time":"2024-05-28T08:00:00+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-2-scaled.jpg","type":"image\/jpeg"}],"author":"Daniel E. Monta\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/daner_004","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Daniel E. Monta\u00f1a","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/"},"author":{"name":"Daniel E. Monta\u00f1a","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/9198e7dbab43c6d74d0fd5399af7c3cd"},"headline":"ASTROCLAP","datePublished":"2024-05-28T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/"},"wordCount":269,"commentCount":0,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-2-scaled.jpg","articleSection":["Arte","Teatro"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/","url":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/","name":"ASTROCLAP - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-2-scaled.jpg","datePublished":"2024-05-28T08:00:00+00:00","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-2-scaled.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/05\/Astroclap-2-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2024\/05\/28\/astroclap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"ASTROCLAP"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista y conductor de radio y televisi\u00f3n argentino, nacido el 6 de septiembre de 1964.","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"]},{"@type":"Person","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/9198e7dbab43c6d74d0fd5399af7c3cd","name":"Daniel E. Monta\u00f1a","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Daniel-150x150.jpg","caption":"Daniel E. Monta\u00f1a"},"sameAs":["https:\/\/facebook.com\/danielernesto.montana","https:\/\/instagram.com\/daniel_montana1961","https:\/\/x.com\/https:\/\/twitter.com\/daner_004"],"url":"https:\/\/sergiolapegue.com\/site\/author\/daniel\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/15183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=15183"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/15183\/revisions"}],"predecessor-version":[{"id":15187,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/15183\/revisions\/15187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/15186"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=15183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=15183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=15183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}