{"id":13271,"date":"2024-02-17T09:13:00","date_gmt":"2024-02-17T12:13:00","guid":{"rendered":"https:\/\/sergiolapegue.com\/site\/?p=13271"},"modified":"2024-02-08T15:18:14","modified_gmt":"2024-02-08T18:18:14","slug":"los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres","status":"publish","type":"post","link":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/","title":{"rendered":"Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres"},"content":{"rendered":"\n<p>Por a\u00f1os, los cient\u00edficos han advertido a los hombres que tienen problemas de fertilidad de que se mantengan alejados de los ba\u00f1os calientes y de los jacuzzis.<\/p>\n\n\n\n<p>Lo anterior, ya que existen razones para sospechar que una larga exposici\u00f3n al agua caliente pod\u00eda causar infertilidad.<\/p>\n\n\n\n<p>Los estudios han demostrado que la cantidad de espermatozoides en los hombres con problemas de fertilidad increment\u00f3 considerablemente despu\u00e9s de que dejaran de ducharse con agua caliente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose01-1024x576.jpg\" alt=\"\" class=\"wp-image-13272\" srcset=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose01-1024x576.jpg 1024w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose01-300x169.jpg 300w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose01-768x432.jpg 768w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose01-696x392.jpg 696w, https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose01.jpg 1068w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>El sobrecalentamiento de los test\u00edculos puede da\u00f1ar la cantidad de espermatozoides y la capacidad reproductiva.<\/p>\n\n\n\n<p>Adem\u00e1s, el agua caliente puede deteriorar las c\u00e9lulas de la piel al afectar a las capas de queratina y eliminar los aceites de la piel, lo que produce sequedad cut\u00e1nea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por a\u00f1os, los cient\u00edficos han advertido a los hombres que tienen problemas de fertilidad de que se mantengan alejados de los ba\u00f1os calientes y de los jacuzzis. Lo anterior, ya que existen razones para sospechar que una larga exposici\u00f3n al agua caliente pod\u00eda causar infertilidad. Los estudios han demostrado que la cantidad de espermatozoides en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[211,1045,1453,2517,2510,157,3271,608,3270,2034,1169,66],"class_list":{"0":"post-13271","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-agua","9":"tag-bano","10":"tag-caliente","11":"tag-cientificos","12":"tag-ducha","13":"tag-enfermedad","14":"tag-espermatozoides","15":"tag-hombre","16":"tag-hot","17":"tag-infertilidad","18":"tag-problemas","19":"tag-salud"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres - Sergio Lapegue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres - Sergio Lapegue\" \/>\n<meta property=\"og:description\" content=\"Por a\u00f1os, los cient\u00edficos han advertido a los hombres que tienen problemas de fertilidad de que se mantengan alejados de los ba\u00f1os calientes y de los jacuzzis. Lo anterior, ya que existen razones para sospechar que una larga exposici\u00f3n al agua caliente pod\u00eda causar infertilidad. Los estudios han demostrado que la cantidad de espermatozoides en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/\" \/>\n<meta property=\"og:site_name\" content=\"Sergio Lapegue\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sergiolapegue\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-17T12:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose02.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1071\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Leonardo Monta\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soytoto81\" \/>\n<meta name=\"twitter:site\" content=\"@sergiolapegue\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonardo Monta\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/\"},\"author\":{\"name\":\"Leonardo Monta\u00f1a\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/00adf937d010c7f79a180dc4916a40e0\"},\"headline\":\"Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres\",\"datePublished\":\"2024-02-17T12:13:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/\"},\"wordCount\":142,\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/hombre-banandose02.webp\",\"keywords\":[\"agua\",\"ba\u00f1o\",\"caliente\",\"cientificos\",\"ducha\",\"enfermedad\",\"espermatozoides\",\"hombre\",\"hot\",\"infertilidad\",\"problemas\",\"salud\"],\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/\",\"name\":\"Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres - Sergio Lapegue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/hombre-banandose02.webp\",\"datePublished\":\"2024-02-17T12:13:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/hombre-banandose02.webp\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/hombre-banandose02.webp\",\"width\":1600,\"height\":1071},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/2024\\\/02\\\/17\\\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/\",\"name\":\"Sergio Lapegue\",\"description\":\"Periodista\",\"publisher\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/083aeceeb0734cd166779ea6c0551a37\",\"name\":\"Sergio Lapegue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\",\"width\":272,\"height\":90,\"caption\":\"Sergio Lapegue\"},\"logo\":{\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo_header-1.png\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/sergiolapegue\",\"https:\\\/\\\/instagram.com\\\/sergiolapegue\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/sergiolapegue\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/#\\\/schema\\\/person\\\/00adf937d010c7f79a180dc4916a40e0\",\"name\":\"Leonardo Monta\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Leonardo-150x150.jpg\",\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Leonardo-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/sl_avatar_Leonardo-150x150.jpg\",\"caption\":\"Leonardo Monta\u00f1a\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soytoto81\"],\"url\":\"https:\\\/\\\/sergiolapegue.com\\\/site\\\/author\\\/leonardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres - Sergio Lapegue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/","og_locale":"es_ES","og_type":"article","og_title":"Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres - Sergio Lapegue","og_description":"Por a\u00f1os, los cient\u00edficos han advertido a los hombres que tienen problemas de fertilidad de que se mantengan alejados de los ba\u00f1os calientes y de los jacuzzis. Lo anterior, ya que existen razones para sospechar que una larga exposici\u00f3n al agua caliente pod\u00eda causar infertilidad. Los estudios han demostrado que la cantidad de espermatozoides en [&hellip;]","og_url":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/","og_site_name":"Sergio Lapegue","article_publisher":"https:\/\/facebook.com\/sergiolapegue","article_published_time":"2024-02-17T12:13:00+00:00","og_image":[{"width":1600,"height":1071,"url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose02.webp","type":"image\/webp"}],"author":"Leonardo Monta\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/soytoto81","twitter_site":"@sergiolapegue","twitter_misc":{"Escrito por":"Leonardo Monta\u00f1a","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/#article","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/"},"author":{"name":"Leonardo Monta\u00f1a","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/00adf937d010c7f79a180dc4916a40e0"},"headline":"Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres","datePublished":"2024-02-17T12:13:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/"},"wordCount":142,"publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose02.webp","keywords":["agua","ba\u00f1o","caliente","cientificos","ducha","enfermedad","espermatozoides","hombre","hot","infertilidad","problemas","salud"],"articleSection":["Actualidad"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/","url":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/","name":"Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres - Sergio Lapegue","isPartOf":{"@id":"https:\/\/sergiolapegue.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/#primaryimage"},"image":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/#primaryimage"},"thumbnailUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose02.webp","datePublished":"2024-02-17T12:13:00+00:00","breadcrumb":{"@id":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/#primaryimage","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose02.webp","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2024\/02\/hombre-banandose02.webp","width":1600,"height":1071},{"@type":"BreadcrumbList","@id":"https:\/\/sergiolapegue.com\/site\/2024\/02\/17\/los-banos-frecuentes-con-agua-caliente-estarian-causando-infertilidad-en-los-hombres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sergiolapegue.com\/site\/"},{"@type":"ListItem","position":2,"name":"Los ba\u00f1os frecuentes con agua caliente estar\u00edan causando infertilidad en los hombres"}]},{"@type":"WebSite","@id":"https:\/\/sergiolapegue.com\/site\/#website","url":"https:\/\/sergiolapegue.com\/site\/","name":"Sergio Lapegue","description":"Periodista","publisher":{"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sergiolapegue.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Person","Organization"],"@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/083aeceeb0734cd166779ea6c0551a37","name":"Sergio Lapegue","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png","width":272,"height":90,"caption":"Sergio Lapegue"},"logo":{"@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/logo_header-1.png"},"sameAs":["https:\/\/facebook.com\/sergiolapegue","https:\/\/instagram.com\/sergiolapegue","https:\/\/x.com\/https:\/\/twitter.com\/sergiolapegue"]},{"@type":"Person","@id":"https:\/\/sergiolapegue.com\/site\/#\/schema\/person\/00adf937d010c7f79a180dc4916a40e0","name":"Leonardo Monta\u00f1a","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Leonardo-150x150.jpg","url":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Leonardo-150x150.jpg","contentUrl":"https:\/\/sergiolapegue.com\/site\/wp-content\/uploads\/2021\/04\/sl_avatar_Leonardo-150x150.jpg","caption":"Leonardo Monta\u00f1a"},"sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/soytoto81"],"url":"https:\/\/sergiolapegue.com\/site\/author\/leonardo\/"}]}},"_links":{"self":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/13271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/comments?post=13271"}],"version-history":[{"count":1,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/13271\/revisions"}],"predecessor-version":[{"id":13274,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/posts\/13271\/revisions\/13274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media\/13273"}],"wp:attachment":[{"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/media?parent=13271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/categories?post=13271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sergiolapegue.com\/site\/wp-json\/wp\/v2\/tags?post=13271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}